{"id":82922,"date":"2024-10-28T13:16:38","date_gmt":"2024-10-28T12:16:38","guid":{"rendered":"https:\/\/conversesacatalunya.cat\/ladeu-de-colau-i-el-futur-del-tramvia-a-barcelona\/"},"modified":"2024-10-28T14:25:43","modified_gmt":"2024-10-28T13:25:43","slug":"el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona","status":"publish","type":"post","link":"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/","title":{"rendered":"El adi\u00f3s de Colau y el futuro del tranv\u00eda en Barcelona"},"content":{"rendered":"<p><span>Colau se ha despedido, y todo el mundo sabe por qu\u00e9. Simplemente, porque se ha visto incapaz de cumplir el compromiso asumido frente a los votantes que la escogieron. Ser oposici\u00f3n en el Ayuntamiento de Barcelona es una tarea dura, mucho m\u00e1s que hacerlo en el Parlament de Catalunya: es un trabajo ingrato, poco reconocido y con escasa atenci\u00f3n medi\u00e1tica.<\/span><\/p>\n<p><span>Colau esper\u00f3 meses desde las elecciones para constatar que\u00a0<\/span><strong><span>no ten\u00eda una salida clara y organizada<\/span><\/strong><span>. Al final, ha decidido dejarlo sin m\u00e1s, esperando mejores tiempos. Lo ha hecho a su manera, en el pleno del pasado viernes 25 de octubre, con un discurso cargado de\u00a0<\/span><strong><span>narcisismo y autocomplacencia<\/span><\/strong><span>, tan rid\u00edculo como puede ser cualquier intento de hacer balance en p\u00fablico despu\u00e9s de unos resultados mediocres. Cabe recordar que Colau fue reelegida alcaldesa en su segundo mandato gracias al controvertido voto de Valls, una estrella fugaz parisina, que nos dej\u00f3 como legado un nuevo mandato de una alcaldesa con un fiel n\u00facleo de incondicionales, pero con la mayor\u00eda de la ciudad en su contra.<\/span><\/p>\n<p><span>Es pertinente recordar tambi\u00e9n que su primera victoria se debi\u00f3, en buena medida, a la decisi\u00f3n del entonces alcalde, Xavier Trias, de no intentar formar una f\u00e1cil coalici\u00f3n con otras fuerzas como los socialistas o Esquerra Republicana.<\/span><\/p>\n<p><span>En su\u00a0<\/span><strong><span>discurso de despedida<\/span><\/strong><span>, Colau habl\u00f3 con un orgullo desmedido, como si hablara en nombre de toda la ciudad, cuando en realidad s\u00f3lo representaba el 12% del electorado. Estas visiones tan egoc\u00e9ntricas dicen mucho sobre las manos en las que ha estado Barcelona durante los \u00faltimos ocho a\u00f1os, y tambi\u00e9n sobre el grado de dependencia de sus subordinados, capaces de asumir tanto ego inadecuado.<\/span><\/p>\n<p><strong><span>La historia municipal de Colau es la de un fracaso<\/span><\/strong><span>. Lleg\u00f3 para resolver el problema de la vivienda, y el balance final habla por s\u00ed mismo. Confundi\u00f3 el urbanismo orientado a mejorar la calidad de vida con la lucha contra el veh\u00edculo privado, ignorando las deficiencias del transporte p\u00fablico, especialmente para entrar y salir de la ciudad. La ciudad empeor\u00f3 en t\u00e9rminos de limpieza y seguridad, levantando la bandera contra el turismo con el resultado de que, al final de su mandato, la ciudad estaba m\u00e1s llena que nunca de turistas.<\/span><\/p>\n<p><span>No es el momento de realizar un balance detallado de su gesti\u00f3n, pero s\u00ed cabe se\u00f1alar el narcisismo de Colau y la toxicidad de su figura cuando se eleva a categor\u00eda pol\u00edtica. Collboni, su sucesor, es el continuador natural de muchos aspectos de la obra de Colau. No podr\u00eda ser de otra forma, ya que fue su primer teniente de alcalde y estuvo sometido a su mandato durante a\u00f1os. Uno de los proyectos de continuidad es el\u00a0<\/span><strong><span>tranv\u00eda<\/span><\/strong><span>, que pronto circular\u00e1 hasta el Eixample. Para completar la idea del \u201ctranv\u00eda por la Diagonal\u201d s\u00f3lo faltar\u00e1 el tramo hasta la plaza Francesc Maci\u00e0, destruyendo la reforma de Trias.<\/span><\/p>\n<p><span>Pero esta prolongaci\u00f3n del tranv\u00eda se lleva a cabo bajo un silencio oscuro sobre sus\u00a0<\/span><a href=\"https:\/\/conversesacatalunya.cat\/es\/sombras-sobre-el-tranvia-de-barcelona-la-sigilosa-operacion-de-una-privatizacion-encubierta\/\" target=\"_blank\" rel=\"noopener\"><strong><span>condiciones econ\u00f3micas<\/span><\/strong><\/a><span>. La inversi\u00f3n p\u00fablica realizada por el Ayuntamiento y la Generalitat queda\u00a0<\/span><strong><span>en manos privadas<\/span><\/strong><span>, ya que \u00e9ste es el r\u00e9gimen de concesi\u00f3n actual. El tranv\u00eda es hoy en d\u00eda un negocio privado en Barcelona. No se trata de oponerse a este tipo de actividades por principio, pero s\u00ed que debe exigirse transparencia:<\/span><\/p>\n<ul>\n<li><strong><span>Aclarar cu\u00e1l ser\u00e1 el r\u00e9gimen definitivo de explotaci\u00f3n del tranv\u00eda<\/span><\/strong><span>: si continuar\u00e1 la concesi\u00f3n actual o se paralizar\u00e1; y, si se mantiene, cu\u00e1les son las condiciones econ\u00f3micas que la rigen, las ventajas para la ciudad, las compensaciones recibidas, la inversi\u00f3n realizada y el cesante lucro.<\/span><\/li>\n<li><strong><span>Hay que hablar de lucro cesante<\/span><\/strong><span>\u00a0porque el tranv\u00eda elimina buena parte del recorrido de varias l\u00edneas de autobuses, reduciendo por tanto los ingresos de la compa\u00f1\u00eda municipal. En este sentido, se est\u00e1 desviando un flujo de ingresos p\u00fablicos hacia una actividad privada, y esto tambi\u00e9n debe conocerse.<\/span><\/li>\n<li><span>Tambi\u00e9n es necesario saber\u00a0<\/span><strong><span>cu\u00e1nto cuesta esta obra<\/span><\/strong><span>, cu\u00e1les son las previsiones sobre el transporte de viajeros, y, cuando empiece a funcionar en noviembre, cu\u00e1les son los resultados reales.<\/span><\/li>\n<li><span>Nunca se ha hecho p\u00fablico un\u00a0<\/span><strong><span>informe sobre el impacto del tranv\u00eda en la movilidad ciudadana<\/span><\/strong><span>, ni sobre la posibilidad de alternativas m\u00e1s econ\u00f3micas y flexibles. La disponibilidad de autobuses de gran capacidad el\u00e9ctricos, junto con la coordinaci\u00f3n semaf\u00f3rica, siempre ha sido una alternativa m\u00e1s econ\u00f3mica y flexible, y quiz\u00e1s por eso no se ha querido mostrar a los ciudadanos.<\/span><\/li>\n<li><span>Una \u00faltima cuesti\u00f3n:\u00a0<\/span><strong><span>la falta de credibilidad de los llamamientos a la participaci\u00f3n<\/span><\/strong><span>, tanto de Colau como de Collboni. Es necesaria una consulta ciudadana para demostrar que la opini\u00f3n contraria al tranv\u00eda, que se manifest\u00f3 durante el mandato del alcalde Hereu y contribuy\u00f3 a su ca\u00edda pol\u00edtica, ya no existe, y que, en esta ocasi\u00f3n, Barcelona votar\u00eda a favor de ese medio de transporte.<\/span><\/li>\n<\/ul>\n<p><span>El refer\u00e9ndum sobre el tranv\u00eda, la transparencia en los datos econ\u00f3micos y financieros, as\u00ed como los estudios sobre movilidad, son tres grandes cuestiones que la ciudadan\u00eda exige a Collboni, quien no puede mirar hacia otro lado y seguir en silencio, arriesg\u00e1ndose a demostrar que la democracia es, en realidad, una partitocracia donde los ganadores se reparten cuotas de poder y favores sin tener en cuenta la opini\u00f3n de los ciudadanos, quienes, al fin y al cabo, somos quienes, con nuestro dinero, hacemos posible su trabajo.<\/span><\/p>\n<div id=\"polls-260\" class=\"wp-polls\">\n\t<form id=\"polls_form_260\" class=\"wp-polls-form\" action=\"\/index.php\" method=\"post\">\n\t\t<p style=\"display: none;\"><input type=\"hidden\" id=\"poll_260_nonce\" name=\"wp-polls-nonce\" value=\"47d987df85\" \/><\/p>\n\t\t<p style=\"display: none;\"><input type=\"hidden\" name=\"poll_id\" value=\"260\" \/><\/p>\n\t\t<p style=\"text-align: center\"><strong>Amb tots els elements que han sortit fins ara, creus que \u00e9s possible que \u00cd\u00f1igo Errej\u00f3n tingui un c\u00e0stig penal?<\/strong><\/p><div id=\"polls-260-ans\" class=\"wp-polls-ans\"><ul class=\"wp-polls-ul\">\n\t\t<li><input type=\"radio\" id=\"poll-answer-732\" name=\"poll_260\" value=\"732\" \/> <label for=\"poll-answer-732\">S\u00ed<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-733\" name=\"poll_260\" value=\"733\" \/> <label for=\"poll-answer-733\">No<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-734\" name=\"poll_260\" value=\"734\" \/> <label for=\"poll-answer-734\">Probablement<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-735\" name=\"poll_260\" value=\"735\" \/> <label for=\"poll-answer-735\">No ho s\u00e9<\/label><\/li>\n\t\t<\/ul><p style=\"text-align: center\"><input type=\"button\" name=\"vote\" value=\"   Vota   \" class=\"Buttons\" onclick=\"poll_vote(260);\" \/><\/p><p style=\"text-align: center\"><a href=\"#ViewPollResults\" onclick=\"poll_result(260); return false;\" title=\"View Results Of This Poll\">Mira els resultats<\/a><\/p><\/div>\n\t<\/form>\n<\/div>\n<div id=\"polls-260-loading\" class=\"wp-polls-loading\"><img decoding=\"async\" data-src=\"https:\/\/conversesacatalunya.cat\/wp-content\/plugins\/wp-polls\/images\/loading.gif\" width=\"16\" height=\"16\" alt=\"Cargando ...\" title=\"Cargando ...\" class=\"wp-polls-image lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 16px; --smush-placeholder-aspect-ratio: 16\/16;\" \/>&nbsp;Cargando ...<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Colau se ha despedido, y todo el mundo sabe por qu\u00e9. Simplemente, porque se ha visto incapaz de cumplir el compromiso asumido frente a los votantes que la escogieron. Ser oposici\u00f3n en el Ayuntamiento de Barcelona es una tarea dura, mucho m\u00e1s que hacerlo en el Parlament de Catalunya: es un trabajo ingrato, poco reconocido y con escasa atenci\u00f3n medi\u00e1tica. Colau esper\u00f3 meses desde las elecciones para constatar que\u00a0no ten\u00eda una salida clara y organizada. Al final, ha decidido dejarlo sin m\u00e1s, esperando mejores tiempos. Lo ha hecho a su manera, en el pleno del pasado viernes 25 de octubre, con un discurso cargado de\u00a0narcisismo y autocomplacencia, tan rid\u00edculo como puede ser cualquier intento de hacer balance en p\u00fablico despu\u00e9s de unos resultados mediocres. Cabe recordar que Colau fue reelegida alcaldesa en su segundo mandato gracias al controvertido voto de Valls, una estrella fugaz parisina, que nos dej\u00f3 como legado un nuevo mandato de una alcaldesa con un fiel n\u00facleo de incondicionales, pero con la mayor\u00eda de la ciudad en su contra. Es pertinente recordar tambi\u00e9n que su primera victoria se debi\u00f3, en buena medida, a la decisi\u00f3n del entonces alcalde, Xavier Trias, de no intentar formar una f\u00e1cil coalici\u00f3n con otras fuerzas como los socialistas o Esquerra Republicana. En su\u00a0discurso de despedida, Colau habl\u00f3 con un orgullo desmedido, como si hablara en nombre de toda la ciudad, cuando en realidad s\u00f3lo representaba el 12% del electorado. Estas visiones tan egoc\u00e9ntricas dicen mucho sobre las manos en las que ha estado Barcelona durante los \u00faltimos ocho a\u00f1os, y tambi\u00e9n sobre el grado de dependencia de sus subordinados, capaces de asumir tanto ego inadecuado. La historia municipal de Colau es la de un fracaso. Lleg\u00f3 para resolver el problema de la vivienda, y el balance final habla por s\u00ed mismo. Confundi\u00f3 el urbanismo orientado a mejorar la calidad de vida con la lucha contra el veh\u00edculo privado, ignorando las deficiencias del transporte p\u00fablico, especialmente para entrar y salir de la ciudad. La ciudad empeor\u00f3 en t\u00e9rminos de limpieza y seguridad, levantando la bandera contra el turismo con el resultado de que, al final de su mandato, la ciudad estaba m\u00e1s llena que nunca de turistas. No es el momento de realizar un balance detallado de su gesti\u00f3n, pero s\u00ed cabe se\u00f1alar el narcisismo de Colau y la toxicidad de su figura cuando se eleva a categor\u00eda pol\u00edtica. Collboni, su sucesor, es el continuador natural de muchos aspectos de la obra de Colau. No podr\u00eda ser de otra forma, ya que fue su primer teniente de alcalde y estuvo sometido a su mandato durante a\u00f1os. Uno de los proyectos de continuidad es el\u00a0tranv\u00eda, que pronto circular\u00e1 hasta el Eixample. Para completar la idea del \u201ctranv\u00eda por la Diagonal\u201d s\u00f3lo faltar\u00e1 el tramo hasta la plaza Francesc Maci\u00e0, destruyendo la reforma de Trias. Pero esta prolongaci\u00f3n del tranv\u00eda se lleva a cabo bajo un silencio oscuro sobre sus\u00a0condiciones econ\u00f3micas. La inversi\u00f3n p\u00fablica realizada por el Ayuntamiento y la Generalitat queda\u00a0en manos privadas, ya que \u00e9ste es el r\u00e9gimen de concesi\u00f3n actual. El tranv\u00eda es hoy en d\u00eda un negocio privado en Barcelona. No se trata de oponerse a este tipo de actividades por principio, pero s\u00ed que debe exigirse transparencia: Aclarar cu\u00e1l ser\u00e1 el r\u00e9gimen definitivo de explotaci\u00f3n del tranv\u00eda: si continuar\u00e1 la concesi\u00f3n actual o se paralizar\u00e1; y, si se mantiene, cu\u00e1les son las condiciones econ\u00f3micas que la rigen, las ventajas para la ciudad, las compensaciones recibidas, la inversi\u00f3n realizada y el cesante lucro. Hay que hablar de lucro cesante\u00a0porque el tranv\u00eda elimina buena parte del recorrido de varias l\u00edneas de autobuses, reduciendo por tanto los ingresos de la compa\u00f1\u00eda municipal. En este sentido, se est\u00e1 desviando un flujo de ingresos p\u00fablicos hacia una actividad privada, y esto tambi\u00e9n debe conocerse. Tambi\u00e9n es necesario saber\u00a0cu\u00e1nto cuesta esta obra, cu\u00e1les son las previsiones sobre el transporte de viajeros, y, cuando empiece a funcionar en noviembre, cu\u00e1les son los resultados reales. Nunca se ha hecho p\u00fablico un\u00a0informe sobre el impacto del tranv\u00eda en la movilidad ciudadana, ni sobre la posibilidad de alternativas m\u00e1s econ\u00f3micas y flexibles. La disponibilidad de autobuses de gran capacidad el\u00e9ctricos, junto con la coordinaci\u00f3n semaf\u00f3rica, siempre ha sido una alternativa m\u00e1s econ\u00f3mica y flexible, y quiz\u00e1s por eso no se ha querido mostrar a los ciudadanos. Una \u00faltima cuesti\u00f3n:\u00a0la falta de credibilidad de los llamamientos a la participaci\u00f3n, tanto de Colau como de Collboni. Es necesaria una consulta ciudadana para demostrar que la opini\u00f3n contraria al tranv\u00eda, que se manifest\u00f3 durante el mandato del alcalde Hereu y contribuy\u00f3 a su ca\u00edda pol\u00edtica, ya no existe, y que, en esta ocasi\u00f3n, Barcelona votar\u00eda a favor de ese medio de transporte. El refer\u00e9ndum sobre el tranv\u00eda, la transparencia en los datos econ\u00f3micos y financieros, as\u00ed como los estudios sobre movilidad, son tres grandes cuestiones que la ciudadan\u00eda exige a Collboni, quien no puede mirar hacia otro lado y seguir en silencio, arriesg\u00e1ndose a demostrar que la democracia es, en realidad, una partitocracia donde los ganadores se reparten cuotas de poder y favores sin tener en cuenta la opini\u00f3n de los ciudadanos, quienes, al fin y al cabo, somos quienes, con nuestro dinero, hacemos posible su trabajo.<\/p>\n","protected":false},"author":77,"featured_media":82919,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","footnotes":""},"categories":[3787,806],"tags":[3776],"class_list":["post-82922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expedient-barcelona-es","category-punts-claus-del-dia-es","tag-tranvia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El adi\u00f3s de Colau y el futuro del tranv\u00eda en Barcelona - Converses a Catalunya<\/title>\n<meta name=\"description\" content=\"El referendo sobre el tranv\u00eda, la transparencia en los datos econ\u00f3micos y financieros, as\u00ed como los estudios sobre movilidad, grandes cuestiones\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El adi\u00f3s de Colau y el futuro del tranv\u00eda en Barcelona - Converses a Catalunya\" \/>\n<meta property=\"og:description\" content=\"El referendo sobre el tranv\u00eda, la transparencia en los datos econ\u00f3micos y financieros, as\u00ed como los estudios sobre movilidad, grandes cuestiones\" \/>\n<meta property=\"og:url\" content=\"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/\" \/>\n<meta property=\"og:site_name\" content=\"Converses a Catalunya\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-28T12:16:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-28T13:25:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2024\/10\/despedida-Colau.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"611\" \/>\n\t<meta property=\"og:image:height\" content=\"422\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Enric Casanovas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Enric Casanovas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/\"},\"author\":{\"name\":\"Enric Casanovas\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/79bd0577b2f3afc8d6519d207c6e8609\"},\"headline\":\"El adi\u00f3s de Colau y el futuro del tranv\u00eda en Barcelona\",\"datePublished\":\"2024-10-28T12:16:38+00:00\",\"dateModified\":\"2024-10-28T13:25:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/\"},\"wordCount\":969,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2024\/10\/despedida-Colau.jpg\",\"keywords\":[\"Tranv\u00eda\"],\"articleSection\":[\"Expedient Barcelona (ES)\",\"Punts clau del dia (ES)\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/\",\"url\":\"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/\",\"name\":\"El adi\u00f3s de Colau y el futuro del tranv\u00eda en Barcelona - Converses a Catalunya\",\"isPartOf\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2024\/10\/despedida-Colau.jpg\",\"datePublished\":\"2024-10-28T12:16:38+00:00\",\"dateModified\":\"2024-10-28T13:25:43+00:00\",\"author\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/79bd0577b2f3afc8d6519d207c6e8609\"},\"description\":\"El referendo sobre el tranv\u00eda, la transparencia en los datos econ\u00f3micos y financieros, as\u00ed como los estudios sobre movilidad, grandes cuestiones\",\"breadcrumb\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/#primaryimage\",\"url\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2024\/10\/despedida-Colau.jpg\",\"contentUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2024\/10\/despedida-Colau.jpg\",\"width\":611,\"height\":422,\"caption\":\"tramvia i Colau\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/conversesacatalunya.cat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El adi\u00f3s de Colau y el futuro del tranv\u00eda en Barcelona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#website\",\"url\":\"https:\/\/conversesacatalunya.cat\/\",\"name\":\"Converses a Catalunya\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/conversesacatalunya.cat\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/79bd0577b2f3afc8d6519d207c6e8609\",\"name\":\"Enric Casanovas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/7ae4379ad4421ec77820e92afd36dd78.jpg?ver=1778583740\",\"contentUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/7ae4379ad4421ec77820e92afd36dd78.jpg?ver=1778583740\",\"caption\":\"Enric Casanovas\"},\"url\":\"https:\/\/conversesacatalunya.cat\/es\/author\/enric-casanovas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El adi\u00f3s de Colau y el futuro del tranv\u00eda en Barcelona - Converses a Catalunya","description":"El referendo sobre el tranv\u00eda, la transparencia en los datos econ\u00f3micos y financieros, as\u00ed como los estudios sobre movilidad, grandes cuestiones","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/","og_locale":"es_ES","og_type":"article","og_title":"El adi\u00f3s de Colau y el futuro del tranv\u00eda en Barcelona - Converses a Catalunya","og_description":"El referendo sobre el tranv\u00eda, la transparencia en los datos econ\u00f3micos y financieros, as\u00ed como los estudios sobre movilidad, grandes cuestiones","og_url":"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/","og_site_name":"Converses a Catalunya","article_published_time":"2024-10-28T12:16:38+00:00","article_modified_time":"2024-10-28T13:25:43+00:00","og_image":[{"width":611,"height":422,"url":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2024\/10\/despedida-Colau.jpg","type":"image\/jpeg"}],"author":"Enric Casanovas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Enric Casanovas","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/#article","isPartOf":{"@id":"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/"},"author":{"name":"Enric Casanovas","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/79bd0577b2f3afc8d6519d207c6e8609"},"headline":"El adi\u00f3s de Colau y el futuro del tranv\u00eda en Barcelona","datePublished":"2024-10-28T12:16:38+00:00","dateModified":"2024-10-28T13:25:43+00:00","mainEntityOfPage":{"@id":"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/"},"wordCount":969,"commentCount":0,"image":{"@id":"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/#primaryimage"},"thumbnailUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2024\/10\/despedida-Colau.jpg","keywords":["Tranv\u00eda"],"articleSection":["Expedient Barcelona (ES)","Punts clau del dia (ES)"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/","url":"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/","name":"El adi\u00f3s de Colau y el futuro del tranv\u00eda en Barcelona - Converses a Catalunya","isPartOf":{"@id":"https:\/\/conversesacatalunya.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/#primaryimage"},"image":{"@id":"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/#primaryimage"},"thumbnailUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2024\/10\/despedida-Colau.jpg","datePublished":"2024-10-28T12:16:38+00:00","dateModified":"2024-10-28T13:25:43+00:00","author":{"@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/79bd0577b2f3afc8d6519d207c6e8609"},"description":"El referendo sobre el tranv\u00eda, la transparencia en los datos econ\u00f3micos y financieros, as\u00ed como los estudios sobre movilidad, grandes cuestiones","breadcrumb":{"@id":"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/#primaryimage","url":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2024\/10\/despedida-Colau.jpg","contentUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2024\/10\/despedida-Colau.jpg","width":611,"height":422,"caption":"tramvia i Colau"},{"@type":"BreadcrumbList","@id":"https:\/\/conversesacatalunya.cat\/es\/el-adios-de-colau-y-el-futuro-del-tranvia-en-barcelona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/conversesacatalunya.cat\/es\/"},{"@type":"ListItem","position":2,"name":"El adi\u00f3s de Colau y el futuro del tranv\u00eda en Barcelona"}]},{"@type":"WebSite","@id":"https:\/\/conversesacatalunya.cat\/#website","url":"https:\/\/conversesacatalunya.cat\/","name":"Converses a Catalunya","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conversesacatalunya.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/79bd0577b2f3afc8d6519d207c6e8609","name":"Enric Casanovas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/image\/","url":"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/7ae4379ad4421ec77820e92afd36dd78.jpg?ver=1778583740","contentUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/7ae4379ad4421ec77820e92afd36dd78.jpg?ver=1778583740","caption":"Enric Casanovas"},"url":"https:\/\/conversesacatalunya.cat\/es\/author\/enric-casanovas\/"}]}},"wps_subtitle":"El referendo sobre el tranv\u00eda, la transparencia en los datos econ\u00f3micos y financieros, as\u00ed como los estudios sobre movilidad, son tres grandes cuestiones que la ciudadan\u00eda exige","_links":{"self":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/82922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/comments?post=82922"}],"version-history":[{"count":2,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/82922\/revisions"}],"predecessor-version":[{"id":82924,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/82922\/revisions\/82924"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/media\/82919"}],"wp:attachment":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/media?parent=82922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/categories?post=82922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/tags?post=82922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}