{"id":79847,"date":"2024-07-12T11:00:51","date_gmt":"2024-07-12T09:00:51","guid":{"rendered":"https:\/\/conversesacatalunya.cat\/?p=79847"},"modified":"2024-07-12T11:00:51","modified_gmt":"2024-07-12T09:00:51","slug":"la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico","status":"publish","type":"post","link":"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/","title":{"rendered":"La gente va a pie, el coche no afloja y alguien tiene que mirar qu\u00e9 pasa con el transporte p\u00fablico"},"content":{"rendered":"<p>Le\u00eddos los datos de la encuesta de movilidad en d\u00eda laborable del \u00c1rea Metropolitana de Barcelona (AMB) sin intenci\u00f3n ideol\u00f3gica ni voluntad de adoctrinamiento, el resultado es muy claro y las pol\u00edticas deben orientarse en funci\u00f3n de este resultado.<\/p>\n<p>Primero, <strong>la mayor\u00eda de la gente se traslada a pie<\/strong>, pr\u00e1cticamente el 50% de los desplazamientos, lo que representa 9,56 millones de viajes. A pesar de este hecho, <strong>el peat\u00f3n es para nuestros gobiernos municipales<\/strong> y de una forma descarnada los de Barcelona, un residuo. Es el \u00abbienqueda\u00bb porque todo est\u00e1 montado en su contra cuando deber\u00eda ser exactamente lo contrario. Es <strong>la forma masiva de desplazarse y tambi\u00e9n la m\u00e1s sana<\/strong>, mucho m\u00e1s que el invento del patinete, que es una m\u00e1quina de fabricar obesos.<\/p>\n<p>El coche representa el 25% de los desplazamientos y 5,56 millones de viajes. Un poco menos que el a\u00f1o pasado y que en 2019, que registr\u00f3 el m\u00e1ximo, 5,91 millones, pero m\u00e1s que todo el periodo anterior desde 2013 hasta 2017. Por lo tanto, la idea de que <strong>el coche ha aflojado<\/strong>, si se mira con la perspectiva de unos a\u00f1os, se ve que no es real.<\/p>\n<p>El transporte p\u00fablico, sin contar Cercan\u00edas, es decir, autob\u00fas, metro y FGC, representa solo el 17,6%, y esta es una anomal\u00eda que significa que <strong>el sistema p\u00fablico no funciona o bien le falta capacidad<\/strong>, no tiene un buen intercambio de medios, no est\u00e1 bien articulado con Cercan\u00edas, el gran ausente de la encuesta, o todo junto. Pero es evidente que <strong>la cifra es rid\u00edculamente baja<\/strong>, m\u00e1s considerando el coste que tiene para el erario p\u00fablico porque el billete que pagamos no lo cubre totalmente.<\/p>\n<p><strong>La bicicleta y el patinete tienen una participaci\u00f3n marginal del 2,4%<\/strong>, y esto significa que apenas llegan al medio mill\u00f3n, pero por razones ideol\u00f3gicas son <strong>la ni\u00f1a de los ojos de los gobiernos municipales<\/strong> que, con esta y otras cuestiones, tienen un empacho de ideolog\u00eda de lo ideol\u00f3gicamente correcto y un d\u00e9ficit de an\u00e1lisis de la realidad. La soluci\u00f3n no es la bicicleta y menos el patinete. <strong>La respuesta es caminar y mejorar el transporte p\u00fablico<\/strong> y no fastidiar mientras tanto a los coches, sino facilitar su actividad, que es la mejor manera para que contaminen menos.<\/p>\n<p>Las motocicletas tampoco aportan una gran respuesta, ya que significan el 4% de los desplazamientos y, por lo tanto, no llegan al mill\u00f3n.<\/p>\n<p>Estas cifras deber\u00edan servir a los poderes municipales y metropolitanos para reordenar de una vez y con ambici\u00f3n la movilidad global del AMB y de Barcelona, y para deshacer burradas como la del Carril Bici de Via Augusta. Tambi\u00e9n deber\u00eda servir para que <strong>la ciudadan\u00eda fuera m\u00e1s consciente de la realidad<\/strong> y actuara organizadamente para conseguir que nos atiendan y nos sirvan como merecemos, empezando por la gente que camina.<\/p>\n<div id=\"polls-249\" class=\"wp-polls\">\n\t<form id=\"polls_form_249\" class=\"wp-polls-form\" action=\"\/index.php\" method=\"post\">\n\t\t<p style=\"display: none;\"><input type=\"hidden\" id=\"poll_249_nonce\" name=\"wp-polls-nonce\" value=\"ca6ab674ad\" \/><\/p>\n\t\t<p style=\"display: none;\"><input type=\"hidden\" name=\"poll_id\" value=\"249\" \/><\/p>\n\t\t<p style=\"text-align: center\"><strong>Creus que Puigdemont tornar\u00e0 ara?<\/strong><\/p><div id=\"polls-249-ans\" class=\"wp-polls-ans\"><ul class=\"wp-polls-ul\">\n\t\t<li><input type=\"radio\" id=\"poll-answer-699\" name=\"poll_249\" value=\"699\" \/> <label for=\"poll-answer-699\">S\u00ed<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-700\" name=\"poll_249\" value=\"700\" \/> <label for=\"poll-answer-700\">No<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-701\" name=\"poll_249\" value=\"701\" \/> <label for=\"poll-answer-701\">No ho s\u00e9<\/label><\/li>\n\t\t<\/ul><p style=\"text-align: center\"><input type=\"button\" name=\"vote\" value=\"   Vota   \" class=\"Buttons\" onclick=\"poll_vote(249);\" \/><\/p><p style=\"text-align: center\"><a href=\"#ViewPollResults\" onclick=\"poll_result(249); return false;\" title=\"View Results Of This Poll\">Mira els resultats<\/a><\/p><\/div>\n\t<\/form>\n<\/div>\n<div id=\"polls-249-loading\" class=\"wp-polls-loading\"><img decoding=\"async\" data-src=\"https:\/\/conversesacatalunya.cat\/wp-content\/plugins\/wp-polls\/images\/loading.gif\" width=\"16\" height=\"16\" alt=\"Cargando ...\" title=\"Cargando ...\" class=\"wp-polls-image lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 16px; --smush-placeholder-aspect-ratio: 16\/16;\" \/>&nbsp;Cargando ...<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Le\u00eddos los datos de la encuesta de movilidad en d\u00eda laborable del \u00c1rea Metropolitana de Barcelona (AMB) sin intenci\u00f3n ideol\u00f3gica ni voluntad de adoctrinamiento, el resultado es muy claro y las pol\u00edticas deben orientarse en funci\u00f3n de este resultado. Primero, la mayor\u00eda de la gente se traslada a pie, pr\u00e1cticamente el 50% de los desplazamientos, lo que representa 9,56 millones de viajes. A pesar de este hecho, el peat\u00f3n es para nuestros gobiernos municipales y de una forma descarnada los de Barcelona, un residuo. Es el \u00abbienqueda\u00bb porque todo est\u00e1 montado en su contra cuando deber\u00eda ser exactamente lo contrario. Es la forma masiva de desplazarse y tambi\u00e9n la m\u00e1s sana, mucho m\u00e1s que el invento del patinete, que es una m\u00e1quina de fabricar obesos. El coche representa el 25% de los desplazamientos y 5,56 millones de viajes. Un poco menos que el a\u00f1o pasado y que en 2019, que registr\u00f3 el m\u00e1ximo, 5,91 millones, pero m\u00e1s que todo el periodo anterior desde 2013 hasta 2017. Por lo tanto, la idea de que el coche ha aflojado, si se mira con la perspectiva de unos a\u00f1os, se ve que no es real. El transporte p\u00fablico, sin contar Cercan\u00edas, es decir, autob\u00fas, metro y FGC, representa solo el 17,6%, y esta es una anomal\u00eda que significa que el sistema p\u00fablico no funciona o bien le falta capacidad, no tiene un buen intercambio de medios, no est\u00e1 bien articulado con Cercan\u00edas, el gran ausente de la encuesta, o todo junto. Pero es evidente que la cifra es rid\u00edculamente baja, m\u00e1s considerando el coste que tiene para el erario p\u00fablico porque el billete que pagamos no lo cubre totalmente. La bicicleta y el patinete tienen una participaci\u00f3n marginal del 2,4%, y esto significa que apenas llegan al medio mill\u00f3n, pero por razones ideol\u00f3gicas son la ni\u00f1a de los ojos de los gobiernos municipales que, con esta y otras cuestiones, tienen un empacho de ideolog\u00eda de lo ideol\u00f3gicamente correcto y un d\u00e9ficit de an\u00e1lisis de la realidad. La soluci\u00f3n no es la bicicleta y menos el patinete. La respuesta es caminar y mejorar el transporte p\u00fablico y no fastidiar mientras tanto a los coches, sino facilitar su actividad, que es la mejor manera para que contaminen menos. Las motocicletas tampoco aportan una gran respuesta, ya que significan el 4% de los desplazamientos y, por lo tanto, no llegan al mill\u00f3n. Estas cifras deber\u00edan servir a los poderes municipales y metropolitanos para reordenar de una vez y con ambici\u00f3n la movilidad global del AMB y de Barcelona, y para deshacer burradas como la del Carril Bici de Via Augusta. Tambi\u00e9n deber\u00eda servir para que la ciudadan\u00eda fuera m\u00e1s consciente de la realidad y actuara organizadamente para conseguir que nos atiendan y nos sirvan como merecemos, empezando por la gente que camina.<\/p>\n","protected":false},"author":77,"featured_media":79852,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","footnotes":""},"categories":[3787,806,781],"tags":[1542,1105],"class_list":["post-79847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expedient-barcelona-es","category-punts-claus-del-dia-es","category-sin-categorizar","tag-movilidad","tag-tmb-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La gente va a pie, el coche no afloja y alguien tiene que mirar qu\u00e9 pasa con el transporte p\u00fablico - Converses a Catalunya<\/title>\n<meta name=\"description\" content=\"Desajustes en la movilidad de Barcelona: peatones ignorados y transporte p\u00fablico deficiente\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La gente va a pie, el coche no afloja y alguien tiene que mirar qu\u00e9 pasa con el transporte p\u00fablico - Converses a Catalunya\" \/>\n<meta property=\"og:description\" content=\"Desajustes en la movilidad de Barcelona: peatones ignorados y transporte p\u00fablico deficiente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/\" \/>\n<meta property=\"og:site_name\" content=\"Converses a Catalunya\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-12T09:00:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2024\/07\/mobilitat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"696\" \/>\n\t<meta property=\"og:image:height\" content=\"363\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Enric Casanovas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Enric Casanovas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/\"},\"author\":{\"name\":\"Enric Casanovas\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/79bd0577b2f3afc8d6519d207c6e8609\"},\"headline\":\"La gente va a pie, el coche no afloja y alguien tiene que mirar qu\u00e9 pasa con el transporte p\u00fablico\",\"datePublished\":\"2024-07-12T09:00:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/\"},\"wordCount\":522,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2024\/07\/mobilitat.jpg\",\"keywords\":[\"Movilidad\",\"TMB\"],\"articleSection\":[\"Expedient Barcelona (ES)\",\"Punts clau del dia (ES)\",\"Sin categorizar\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/\",\"url\":\"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/\",\"name\":\"La gente va a pie, el coche no afloja y alguien tiene que mirar qu\u00e9 pasa con el transporte p\u00fablico - Converses a Catalunya\",\"isPartOf\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2024\/07\/mobilitat.jpg\",\"datePublished\":\"2024-07-12T09:00:51+00:00\",\"author\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/79bd0577b2f3afc8d6519d207c6e8609\"},\"description\":\"Desajustes en la movilidad de Barcelona: peatones ignorados y transporte p\u00fablico deficiente\",\"breadcrumb\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/#primaryimage\",\"url\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2024\/07\/mobilitat.jpg\",\"contentUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2024\/07\/mobilitat.jpg\",\"width\":696,\"height\":363},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/conversesacatalunya.cat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La gente va a pie, el coche no afloja y alguien tiene que mirar qu\u00e9 pasa con el transporte p\u00fablico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#website\",\"url\":\"https:\/\/conversesacatalunya.cat\/\",\"name\":\"Converses a Catalunya\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/conversesacatalunya.cat\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/79bd0577b2f3afc8d6519d207c6e8609\",\"name\":\"Enric Casanovas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/7ae4379ad4421ec77820e92afd36dd78.jpg?ver=1778583740\",\"contentUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/7ae4379ad4421ec77820e92afd36dd78.jpg?ver=1778583740\",\"caption\":\"Enric Casanovas\"},\"url\":\"https:\/\/conversesacatalunya.cat\/es\/author\/enric-casanovas\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La gente va a pie, el coche no afloja y alguien tiene que mirar qu\u00e9 pasa con el transporte p\u00fablico - Converses a Catalunya","description":"Desajustes en la movilidad de Barcelona: peatones ignorados y transporte p\u00fablico deficiente","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/","og_locale":"es_ES","og_type":"article","og_title":"La gente va a pie, el coche no afloja y alguien tiene que mirar qu\u00e9 pasa con el transporte p\u00fablico - Converses a Catalunya","og_description":"Desajustes en la movilidad de Barcelona: peatones ignorados y transporte p\u00fablico deficiente","og_url":"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/","og_site_name":"Converses a Catalunya","article_published_time":"2024-07-12T09:00:51+00:00","og_image":[{"width":696,"height":363,"url":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2024\/07\/mobilitat.jpg","type":"image\/jpeg"}],"author":"Enric Casanovas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Enric Casanovas","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/#article","isPartOf":{"@id":"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/"},"author":{"name":"Enric Casanovas","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/79bd0577b2f3afc8d6519d207c6e8609"},"headline":"La gente va a pie, el coche no afloja y alguien tiene que mirar qu\u00e9 pasa con el transporte p\u00fablico","datePublished":"2024-07-12T09:00:51+00:00","mainEntityOfPage":{"@id":"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/"},"wordCount":522,"commentCount":0,"image":{"@id":"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/#primaryimage"},"thumbnailUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2024\/07\/mobilitat.jpg","keywords":["Movilidad","TMB"],"articleSection":["Expedient Barcelona (ES)","Punts clau del dia (ES)","Sin categorizar"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/","url":"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/","name":"La gente va a pie, el coche no afloja y alguien tiene que mirar qu\u00e9 pasa con el transporte p\u00fablico - Converses a Catalunya","isPartOf":{"@id":"https:\/\/conversesacatalunya.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/#primaryimage"},"image":{"@id":"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/#primaryimage"},"thumbnailUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2024\/07\/mobilitat.jpg","datePublished":"2024-07-12T09:00:51+00:00","author":{"@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/79bd0577b2f3afc8d6519d207c6e8609"},"description":"Desajustes en la movilidad de Barcelona: peatones ignorados y transporte p\u00fablico deficiente","breadcrumb":{"@id":"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/#primaryimage","url":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2024\/07\/mobilitat.jpg","contentUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2024\/07\/mobilitat.jpg","width":696,"height":363},{"@type":"BreadcrumbList","@id":"https:\/\/conversesacatalunya.cat\/es\/la-gente-va-a-pie-el-coche-no-afloja-y-alguien-tiene-que-mirar-que-pasa-con-el-transporte-publico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/conversesacatalunya.cat\/es\/"},{"@type":"ListItem","position":2,"name":"La gente va a pie, el coche no afloja y alguien tiene que mirar qu\u00e9 pasa con el transporte p\u00fablico"}]},{"@type":"WebSite","@id":"https:\/\/conversesacatalunya.cat\/#website","url":"https:\/\/conversesacatalunya.cat\/","name":"Converses a Catalunya","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conversesacatalunya.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/79bd0577b2f3afc8d6519d207c6e8609","name":"Enric Casanovas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/image\/","url":"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/7ae4379ad4421ec77820e92afd36dd78.jpg?ver=1778583740","contentUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/7ae4379ad4421ec77820e92afd36dd78.jpg?ver=1778583740","caption":"Enric Casanovas"},"url":"https:\/\/conversesacatalunya.cat\/es\/author\/enric-casanovas\/"}]}},"wps_subtitle":"Desajustes en la movilidad de Barcelona: peatones ignorados y transporte p\u00fablico deficiente","_links":{"self":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/79847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/comments?post=79847"}],"version-history":[{"count":2,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/79847\/revisions"}],"predecessor-version":[{"id":79854,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/79847\/revisions\/79854"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/media\/79852"}],"wp:attachment":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/media?parent=79847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/categories?post=79847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/tags?post=79847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}