{"id":69345,"date":"2023-07-18T09:51:29","date_gmt":"2023-07-18T07:51:29","guid":{"rendered":"https:\/\/conversesacatalunya.cat\/?p=69345"},"modified":"2023-07-18T09:51:29","modified_gmt":"2023-07-18T07:51:29","slug":"las-amenazas-de-la-ia","status":"publish","type":"post","link":"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/","title":{"rendered":"Las amenazas de la IA (Domingo Mart\u00ednez)"},"content":{"rendered":"<p>Una carta abierta, suscrita por 350 cient\u00edficos y especialistas en la investigaci\u00f3n y desarrollo de la Inteligencia Artificial (IA), advierte con tintes dram\u00e1ticos que este nuevo instrumento tecnol\u00f3gico representa riesgos serios que <strong>deben ser controlados como se hace con las pandemias o la bomba at\u00f3mica.<\/strong><\/p>\n<p>La advertencia ha sido apoyada tambi\u00e9n por algunas de las empresas l\u00edderes en el desarrollo de esta tecnolog\u00eda de la cuarta revoluci\u00f3n industrial.<\/p>\n<p>Hace tan s\u00f3lo dos meses, otros 1.300 investigadores y empresarios, entre los que destaca el propio cofundador de la Inteligencia Artificial, el controvertido multimillonario <strong>Elon Musk<\/strong>, hab\u00edan solicitado una moratoria de seis meses en las investigaciones de laboratorio para dedicarse a pensar m\u00e1s sobre los riesgos ahora denunciados.<\/p>\n<p>Entre los peligros denunciados que comporta la Inteligencia Artificial (IA), se habla de la <strong>suplantaci\u00f3n de profesionales<\/strong> de numerosos \u00e1mbitos por robots aut\u00f3nomos, la provocaci\u00f3n de accidentes, los usos perversos por parte de desaprensivos y, sobre todo, en la proliferaci\u00f3n de nuevas armas.<\/p>\n<p><strong>La Santa Sede ya propuso en el seno de la ONU<\/strong> la fundaci\u00f3n de un organismo mundial que analice y controle esta nueva tecnolog\u00eda y el Papa Francisco ha pedido mucha cautela a la hora de confiar juicios a algoritmos que procesan datos recogidos sobre algunas entidades y sobre las personas.<\/p>\n<p>La Inteligencia Artificial ofrecer\u00e1, sin duda, muchas aportaciones positivas a numerosos campos, y no debemos cultivar la nostalgia de un mundo sin m\u00e1quinas. <strong>Se trata de no convertirla en un \u00eddolo ni en una realidad que escape de cualquier instancia \u00e9tica<\/strong> y, en mi opini\u00f3n, del necesario control democr\u00e1tico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una carta abierta, suscrita por 350 cient\u00edficos y especialistas en la investigaci\u00f3n y desarrollo de la Inteligencia Artificial (IA), advierte con tintes dram\u00e1ticos que este nuevo instrumento tecnol\u00f3gico representa riesgos serios que deben ser controlados como se hace con las pandemias o la bomba at\u00f3mica. La advertencia ha sido apoyada tambi\u00e9n por algunas de las empresas l\u00edderes en el desarrollo de esta tecnolog\u00eda de la cuarta revoluci\u00f3n industrial. Hace tan s\u00f3lo dos meses, otros 1.300 investigadores y empresarios, entre los que destaca el propio cofundador de la Inteligencia Artificial, el controvertido multimillonario Elon Musk, hab\u00edan solicitado una moratoria de seis meses en las investigaciones de laboratorio para dedicarse a pensar m\u00e1s sobre los riesgos ahora denunciados. Entre los peligros denunciados que comporta la Inteligencia Artificial (IA), se habla de la suplantaci\u00f3n de profesionales de numerosos \u00e1mbitos por robots aut\u00f3nomos, la provocaci\u00f3n de accidentes, los usos perversos por parte de desaprensivos y, sobre todo, en la proliferaci\u00f3n de nuevas armas. La Santa Sede ya propuso en el seno de la ONU la fundaci\u00f3n de un organismo mundial que analice y controle esta nueva tecnolog\u00eda y el Papa Francisco ha pedido mucha cautela a la hora de confiar juicios a algoritmos que procesan datos recogidos sobre algunas entidades y sobre las personas. La Inteligencia Artificial ofrecer\u00e1, sin duda, muchas aportaciones positivas a numerosos campos, y no debemos cultivar la nostalgia de un mundo sin m\u00e1quinas. Se trata de no convertirla en un \u00eddolo ni en una realidad que escape de cualquier instancia \u00e9tica y, en mi opini\u00f3n, del necesario control democr\u00e1tico.<\/p>\n","protected":false},"author":3,"featured_media":69340,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","footnotes":""},"categories":[802],"tags":[1637],"class_list":["post-69345","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-els-lectors-participen-es","tag-intelligencia-artificial-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las amenazas de la IA (Domingo Mart\u00ednez) - Converses a Catalunya<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las amenazas de la IA (Domingo Mart\u00ednez) - Converses a Catalunya\" \/>\n<meta property=\"og:description\" content=\"Una carta abierta, suscrita por 350 cient\u00edficos y especialistas en la investigaci\u00f3n y desarrollo de la Inteligencia Artificial (IA), advierte con tintes dram\u00e1ticos que este nuevo instrumento tecnol\u00f3gico representa riesgos serios que deben ser controlados como se hace con las pandemias o la bomba at\u00f3mica. La advertencia ha sido apoyada tambi\u00e9n por algunas de las empresas l\u00edderes en el desarrollo de esta tecnolog\u00eda de la cuarta revoluci\u00f3n industrial. Hace tan s\u00f3lo dos meses, otros 1.300 investigadores y empresarios, entre los que destaca el propio cofundador de la Inteligencia Artificial, el controvertido multimillonario Elon Musk, hab\u00edan solicitado una moratoria de seis meses en las investigaciones de laboratorio para dedicarse a pensar m\u00e1s sobre los riesgos ahora denunciados. Entre los peligros denunciados que comporta la Inteligencia Artificial (IA), se habla de la suplantaci\u00f3n de profesionales de numerosos \u00e1mbitos por robots aut\u00f3nomos, la provocaci\u00f3n de accidentes, los usos perversos por parte de desaprensivos y, sobre todo, en la proliferaci\u00f3n de nuevas armas. La Santa Sede ya propuso en el seno de la ONU la fundaci\u00f3n de un organismo mundial que analice y controle esta nueva tecnolog\u00eda y el Papa Francisco ha pedido mucha cautela a la hora de confiar juicios a algoritmos que procesan datos recogidos sobre algunas entidades y sobre las personas. La Inteligencia Artificial ofrecer\u00e1, sin duda, muchas aportaciones positivas a numerosos campos, y no debemos cultivar la nostalgia de un mundo sin m\u00e1quinas. Se trata de no convertirla en un \u00eddolo ni en una realidad que escape de cualquier instancia \u00e9tica y, en mi opini\u00f3n, del necesario control democr\u00e1tico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/\" \/>\n<meta property=\"og:site_name\" content=\"Converses a Catalunya\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-18T07:51:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2023\/07\/technology-g54ee77687_1280.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"684\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"conversesacatalunya\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"conversesacatalunya\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/\"},\"author\":{\"name\":\"conversesacatalunya\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/982274792508d804a0821b413c9ac076\"},\"headline\":\"Las amenazas de la IA (Domingo Mart\u00ednez)\",\"datePublished\":\"2023-07-18T07:51:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/\"},\"wordCount\":286,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2023\/07\/technology-g54ee77687_1280.jpg\",\"keywords\":[\"intel\u00b7lig\u00e8ncia artificial\"],\"articleSection\":[\"Els lectors participen (ES)\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/\",\"url\":\"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/\",\"name\":\"Las amenazas de la IA (Domingo Mart\u00ednez) - Converses a Catalunya\",\"isPartOf\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2023\/07\/technology-g54ee77687_1280.jpg\",\"datePublished\":\"2023-07-18T07:51:29+00:00\",\"author\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/982274792508d804a0821b413c9ac076\"},\"breadcrumb\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/#primaryimage\",\"url\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2023\/07\/technology-g54ee77687_1280.jpg\",\"contentUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2023\/07\/technology-g54ee77687_1280.jpg\",\"width\":1280,\"height\":684},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/conversesacatalunya.cat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las amenazas de la IA (Domingo Mart\u00ednez)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#website\",\"url\":\"https:\/\/conversesacatalunya.cat\/\",\"name\":\"Converses a Catalunya\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/conversesacatalunya.cat\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/982274792508d804a0821b413c9ac076\",\"name\":\"conversesacatalunya\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8449237fd6d6ef5fd54293a157bc8885?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8449237fd6d6ef5fd54293a157bc8885?s=96&d=mm&r=g\",\"caption\":\"conversesacatalunya\"},\"url\":\"https:\/\/conversesacatalunya.cat\/es\/author\/muntsa_escola\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las amenazas de la IA (Domingo Mart\u00ednez) - Converses a Catalunya","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Las amenazas de la IA (Domingo Mart\u00ednez) - Converses a Catalunya","og_description":"Una carta abierta, suscrita por 350 cient\u00edficos y especialistas en la investigaci\u00f3n y desarrollo de la Inteligencia Artificial (IA), advierte con tintes dram\u00e1ticos que este nuevo instrumento tecnol\u00f3gico representa riesgos serios que deben ser controlados como se hace con las pandemias o la bomba at\u00f3mica. La advertencia ha sido apoyada tambi\u00e9n por algunas de las empresas l\u00edderes en el desarrollo de esta tecnolog\u00eda de la cuarta revoluci\u00f3n industrial. Hace tan s\u00f3lo dos meses, otros 1.300 investigadores y empresarios, entre los que destaca el propio cofundador de la Inteligencia Artificial, el controvertido multimillonario Elon Musk, hab\u00edan solicitado una moratoria de seis meses en las investigaciones de laboratorio para dedicarse a pensar m\u00e1s sobre los riesgos ahora denunciados. Entre los peligros denunciados que comporta la Inteligencia Artificial (IA), se habla de la suplantaci\u00f3n de profesionales de numerosos \u00e1mbitos por robots aut\u00f3nomos, la provocaci\u00f3n de accidentes, los usos perversos por parte de desaprensivos y, sobre todo, en la proliferaci\u00f3n de nuevas armas. La Santa Sede ya propuso en el seno de la ONU la fundaci\u00f3n de un organismo mundial que analice y controle esta nueva tecnolog\u00eda y el Papa Francisco ha pedido mucha cautela a la hora de confiar juicios a algoritmos que procesan datos recogidos sobre algunas entidades y sobre las personas. La Inteligencia Artificial ofrecer\u00e1, sin duda, muchas aportaciones positivas a numerosos campos, y no debemos cultivar la nostalgia de un mundo sin m\u00e1quinas. Se trata de no convertirla en un \u00eddolo ni en una realidad que escape de cualquier instancia \u00e9tica y, en mi opini\u00f3n, del necesario control democr\u00e1tico.","og_url":"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/","og_site_name":"Converses a Catalunya","article_published_time":"2023-07-18T07:51:29+00:00","og_image":[{"width":1280,"height":684,"url":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2023\/07\/technology-g54ee77687_1280.jpg","type":"image\/jpeg"}],"author":"conversesacatalunya","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"conversesacatalunya","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/#article","isPartOf":{"@id":"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/"},"author":{"name":"conversesacatalunya","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/982274792508d804a0821b413c9ac076"},"headline":"Las amenazas de la IA (Domingo Mart\u00ednez)","datePublished":"2023-07-18T07:51:29+00:00","mainEntityOfPage":{"@id":"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/"},"wordCount":286,"commentCount":0,"image":{"@id":"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/#primaryimage"},"thumbnailUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2023\/07\/technology-g54ee77687_1280.jpg","keywords":["intel\u00b7lig\u00e8ncia artificial"],"articleSection":["Els lectors participen (ES)"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/","url":"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/","name":"Las amenazas de la IA (Domingo Mart\u00ednez) - Converses a Catalunya","isPartOf":{"@id":"https:\/\/conversesacatalunya.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/#primaryimage"},"image":{"@id":"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/#primaryimage"},"thumbnailUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2023\/07\/technology-g54ee77687_1280.jpg","datePublished":"2023-07-18T07:51:29+00:00","author":{"@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/982274792508d804a0821b413c9ac076"},"breadcrumb":{"@id":"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/#primaryimage","url":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2023\/07\/technology-g54ee77687_1280.jpg","contentUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2023\/07\/technology-g54ee77687_1280.jpg","width":1280,"height":684},{"@type":"BreadcrumbList","@id":"https:\/\/conversesacatalunya.cat\/es\/las-amenazas-de-la-ia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/conversesacatalunya.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Las amenazas de la IA (Domingo Mart\u00ednez)"}]},{"@type":"WebSite","@id":"https:\/\/conversesacatalunya.cat\/#website","url":"https:\/\/conversesacatalunya.cat\/","name":"Converses a Catalunya","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conversesacatalunya.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/982274792508d804a0821b413c9ac076","name":"conversesacatalunya","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8449237fd6d6ef5fd54293a157bc8885?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8449237fd6d6ef5fd54293a157bc8885?s=96&d=mm&r=g","caption":"conversesacatalunya"},"url":"https:\/\/conversesacatalunya.cat\/es\/author\/muntsa_escola\/"}]}},"wps_subtitle":"La Santa Sede ya propuso en el seno de la ONU la fundaci\u00f3n de un organismo mundial que analice y controle esta nueva tecnolog\u00eda","_links":{"self":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/69345","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/comments?post=69345"}],"version-history":[{"count":4,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/69345\/revisions"}],"predecessor-version":[{"id":69349,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/69345\/revisions\/69349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/media\/69340"}],"wp:attachment":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/media?parent=69345"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/categories?post=69345"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/tags?post=69345"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}