{"id":61833,"date":"2022-10-27T12:19:05","date_gmt":"2022-10-27T10:19:05","guid":{"rendered":"https:\/\/conversesacatalunya.cat\/el-gran-abus-dels-impostos\/"},"modified":"2022-10-27T12:26:31","modified_gmt":"2022-10-27T10:26:31","slug":"el-gran-abuso-de-los-impuestos","status":"publish","type":"post","link":"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/","title":{"rendered":"El gran abuso de los impuestos"},"content":{"rendered":"<p><em>Publicado en La Vanguardia el 24-10-2022<\/em><\/p>\n<p>\u00bfPagamos pocos impuestos? Los estatalistas dicen que s\u00ed, porque se recauda el 36,8% del PIB, por el 40,2% en la uni\u00f3n europea. Pero esto no significa que paguemos poco, sino que unos pagan, otros se escaquean y el dise\u00f1o fiscal est\u00e1 lleno de agujeros.<\/p>\n<p>Debemos exigir que la fiscalidad se aborde desde la previa de la eficiencia en la recaudaci\u00f3n y en el gasto p\u00fablico. De no hacerlo as\u00ed, el debate est\u00e1 falseado, porque la condici\u00f3n necesaria para que un estado sea justo es que sea eficiente en la recaudaci\u00f3n y en el gasto, y Espa\u00f1a est\u00e1 escandalosamente lejos de serlo.<\/p>\n<p>Los que pagamos lo hacemos en una medida muy elevada. El m\u00e1ximo por IRPF en Espa\u00f1a se sit\u00faa en el 49,1%, diez puntos m\u00e1s que en la UE. En sociedades, el tipo nominal espa\u00f1ol es del 25%, y en la UE, del 21,3%. Solo en el IVA estamos algo por encima; del 21% al 21,5%. En Europa se recauda de media un 9,9% por la v\u00eda del IRPF y en Espa\u00f1a el 8,8%. Por sociedades, el 2,45% en Europa por el 2% en Espa\u00f1a. Solo en IVA \u2013un impuesto regresivo\u2013 superamos a la media europea; 6,9% por 6,3%. Si en Espa\u00f1a los tipos son m\u00e1s altos en dos de los grandes impuestos y la recaudaci\u00f3n es menor, la causa no es que paguemos menos que en Europa, sino la ineficiencia de la Administraci\u00f3n.<\/p>\n<p>Por si no bastara, la cu\u00f1a fiscal, lo que pagamos por IRPF y a la seguridad social, est\u00e1 por encima de la media de la OCDE, dedic\u00e1ndole cuatro de cada diez euros de nuestro ingreso salarial. Una cu\u00f1a que crece con el presupuesto del 2023, al aumentar la base m\u00e1xima de cotizaci\u00f3n de la seguridad social un 8,6%; en realidad un 9,3% por el 0,6% del mecanismo de equidad intergeneracional.<br \/>\nEl conjunto de impuestos sobre la riqueza (inmuebles, patrimonio, sucesiones y donaciones) es del 2,42% en la zona euro, por el 2,68% en Espa\u00f1a, m\u00e1s que Dinamarca (2,64%) y Suecia (1,05%). Solo nos superan Francia, B\u00e9lgica y Grecia. Para redondearlo, el proyecto de presupuestos del estado establece un aumento del impuesto de la plusval\u00eda que puede alcanzar el 50%.<\/p>\n<p>La presi\u00f3n fiscal se ha venido incrementando desde el 2009, y ahora la inflaci\u00f3n nos obliga a pagar m\u00e1s ganando lo mismo, ha devaluado en un 20% el valor inmobiliario y ha degradado los Ahorros y su rentabilidad. El m\u00e1ximo beneficiario es el estado, que ingresar\u00e1, seg\u00fan Hacienda, 30.000 millones m\u00e1s. Despu\u00e9s, S\u00e1nchez devuelve solo una parte, present\u00e1ndolo casi como un esfuerzo personal.<\/p>\n<p>Los grandes perjudicados de toda esta historia son el \u201cpueblo del IRPF\u201d, la clase media que paga y no recibe, y las rentas inferiores, a causa del efecto del IVA, un impuesto que ser\u00e1 todo lo neutral que se quiera en t\u00e9rminos t\u00e9cnicos, pero que castiga m\u00e1s a quienes menos tienen.<\/p>\n<p>En el otro lado de la balanza, la ineficacia: los siete informes de la Autoridad Independiente de responsabilidad Fiscal (Airef) indican que las administraciones p\u00fablicas malgastan un m\u00ednimo de 10.086 millones. El estudio Eficiencia del gasto p\u00fablico. Medici\u00f3n y propuestas de mejora del Instituto de estudios econ\u00f3micos (IEE) se\u00f1ala que la eficiencia deber\u00eda crecer un 4% para lograr la media de la UE, y un 14% para alcanzar el promedio de la OCDE, equivalente a entre 8.000 y 27.751 millones del gasto no financiero del 2023, y todo ello cuando el salario medio del sector p\u00fablico es un 58% superior al del sector privado, sin riesgo de despido. Pero la exuberancia en el gasto no ceja. Seg\u00fan Fedea, desde el 2018 el gasto p\u00fablico ha crecido 6,6 veces m\u00e1s que el PIB. Resultado: la pesada losa de la deuda que, sobre todo, depositamos sobre las espaldas de nuestros j\u00f3venes. Hay en esto, las pensiones, el paro juvenil (26,6%) y la incapacidad para atenuarla crisis del clima, una tremenda ruptura de la solidaridad entre generaciones.<\/p>\n<p>Es un gran abuso, que solo puede repararse a corto plazo, deflactando \u2013descontando la inflaci\u00f3n\u2013 del IRPF con criterio redistributivo, suprimiendo el impuesto del patrimonio y anulando los incrementos de la plusval\u00eda para el 2023. Esto y cumplir la promesa olvidada de S\u00e1nchez, de una reforma del sistema fiscal, ahora convertido en un sistema Frankenstein a base de acumular retoques, junto con una reforma de la Administraci\u00f3n del estado para lograr que sea eficiente en el gasto y la recaudaci\u00f3n.<\/p>\n<p>Trabajamos siete meses al a\u00f1o para pagar los impuestos, y a\u00fan no les basta. Se\u00f1oras y se\u00f1ores, todo esto es un abuso. Y en Catalunya todav\u00eda m\u00e1s.<\/p>\n<div id=\"polls-171\" class=\"wp-polls\">\n\t<form id=\"polls_form_171\" class=\"wp-polls-form\" action=\"\/index.php\" method=\"post\">\n\t\t<p style=\"display: none;\"><input type=\"hidden\" id=\"poll_171_nonce\" name=\"wp-polls-nonce\" value=\"651cd4e21e\" \/><\/p>\n\t\t<p style=\"display: none;\"><input type=\"hidden\" name=\"poll_id\" value=\"171\" \/><\/p>\n\t\t<p style=\"text-align: center\"><strong>Colau ha afirmat des de l'Argentina que a Barcelona es crearan 45.000 nous llocs de treball gr\u00e0cies a l'acci\u00f3 municipal. Creus que \u00e9s una promesa electoralista?<\/strong><\/p><div id=\"polls-171-ans\" class=\"wp-polls-ans\"><ul class=\"wp-polls-ul\">\n\t\t<li><input type=\"radio\" id=\"poll-answer-453\" name=\"poll_171\" value=\"453\" \/> <label for=\"poll-answer-453\">S\u00ed<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-454\" name=\"poll_171\" value=\"454\" \/> <label for=\"poll-answer-454\">No<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-455\" name=\"poll_171\" value=\"455\" \/> <label for=\"poll-answer-455\">No ho s\u00e9<\/label><\/li>\n\t\t<\/ul><p style=\"text-align: center\"><input type=\"button\" name=\"vote\" value=\"   Vota   \" class=\"Buttons\" onclick=\"poll_vote(171);\" \/><\/p><p style=\"text-align: center\"><a href=\"#ViewPollResults\" onclick=\"poll_result(171); return false;\" title=\"View Results Of This Poll\">Mira els resultats<\/a><\/p><\/div>\n\t<\/form>\n<\/div>\n<div id=\"polls-171-loading\" class=\"wp-polls-loading\"><img decoding=\"async\" data-src=\"https:\/\/conversesacatalunya.cat\/wp-content\/plugins\/wp-polls\/images\/loading.gif\" width=\"16\" height=\"16\" alt=\"Cargando ...\" title=\"Cargando ...\" class=\"wp-polls-image lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 16px; --smush-placeholder-aspect-ratio: 16\/16;\" \/>&nbsp;Cargando ...<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Publicado en La Vanguardia el 24-10-2022 \u00bfPagamos pocos impuestos? Los estatalistas dicen que s\u00ed, porque se recauda el 36,8% del PIB, por el 40,2% en la uni\u00f3n europea. Pero esto no significa que paguemos poco, sino que unos pagan, otros se escaquean y el dise\u00f1o fiscal est\u00e1 lleno de agujeros. Debemos exigir que la fiscalidad se aborde desde la previa de la eficiencia en la recaudaci\u00f3n y en el gasto p\u00fablico. De no hacerlo as\u00ed, el debate est\u00e1 falseado, porque la condici\u00f3n necesaria para que un estado sea justo es que sea eficiente en la recaudaci\u00f3n y en el gasto, y Espa\u00f1a est\u00e1 escandalosamente lejos de serlo. Los que pagamos lo hacemos en una medida muy elevada. El m\u00e1ximo por IRPF en Espa\u00f1a se sit\u00faa en el 49,1%, diez puntos m\u00e1s que en la UE. En sociedades, el tipo nominal espa\u00f1ol es del 25%, y en la UE, del 21,3%. Solo en el IVA estamos algo por encima; del 21% al 21,5%. En Europa se recauda de media un 9,9% por la v\u00eda del IRPF y en Espa\u00f1a el 8,8%. Por sociedades, el 2,45% en Europa por el 2% en Espa\u00f1a. Solo en IVA \u2013un impuesto regresivo\u2013 superamos a la media europea; 6,9% por 6,3%. Si en Espa\u00f1a los tipos son m\u00e1s altos en dos de los grandes impuestos y la recaudaci\u00f3n es menor, la causa no es que paguemos menos que en Europa, sino la ineficiencia de la Administraci\u00f3n. Por si no bastara, la cu\u00f1a fiscal, lo que pagamos por IRPF y a la seguridad social, est\u00e1 por encima de la media de la OCDE, dedic\u00e1ndole cuatro de cada diez euros de nuestro ingreso salarial. Una cu\u00f1a que crece con el presupuesto del 2023, al aumentar la base m\u00e1xima de cotizaci\u00f3n de la seguridad social un 8,6%; en realidad un 9,3% por el 0,6% del mecanismo de equidad intergeneracional. El conjunto de impuestos sobre la riqueza (inmuebles, patrimonio, sucesiones y donaciones) es del 2,42% en la zona euro, por el 2,68% en Espa\u00f1a, m\u00e1s que Dinamarca (2,64%) y Suecia (1,05%). Solo nos superan Francia, B\u00e9lgica y Grecia. Para redondearlo, el proyecto de presupuestos del estado establece un aumento del impuesto de la plusval\u00eda que puede alcanzar el 50%. La presi\u00f3n fiscal se ha venido incrementando desde el 2009, y ahora la inflaci\u00f3n nos obliga a pagar m\u00e1s ganando lo mismo, ha devaluado en un 20% el valor inmobiliario y ha degradado los Ahorros y su rentabilidad. El m\u00e1ximo beneficiario es el estado, que ingresar\u00e1, seg\u00fan Hacienda, 30.000 millones m\u00e1s. Despu\u00e9s, S\u00e1nchez devuelve solo una parte, present\u00e1ndolo casi como un esfuerzo personal. Los grandes perjudicados de toda esta historia son el \u201cpueblo del IRPF\u201d, la clase media que paga y no recibe, y las rentas inferiores, a causa del efecto del IVA, un impuesto que ser\u00e1 todo lo neutral que se quiera en t\u00e9rminos t\u00e9cnicos, pero que castiga m\u00e1s a quienes menos tienen. En el otro lado de la balanza, la ineficacia: los siete informes de la Autoridad Independiente de responsabilidad Fiscal (Airef) indican que las administraciones p\u00fablicas malgastan un m\u00ednimo de 10.086 millones. El estudio Eficiencia del gasto p\u00fablico. Medici\u00f3n y propuestas de mejora del Instituto de estudios econ\u00f3micos (IEE) se\u00f1ala que la eficiencia deber\u00eda crecer un 4% para lograr la media de la UE, y un 14% para alcanzar el promedio de la OCDE, equivalente a entre 8.000 y 27.751 millones del gasto no financiero del 2023, y todo ello cuando el salario medio del sector p\u00fablico es un 58% superior al del sector privado, sin riesgo de despido. Pero la exuberancia en el gasto no ceja. Seg\u00fan Fedea, desde el 2018 el gasto p\u00fablico ha crecido 6,6 veces m\u00e1s que el PIB. Resultado: la pesada losa de la deuda que, sobre todo, depositamos sobre las espaldas de nuestros j\u00f3venes. Hay en esto, las pensiones, el paro juvenil (26,6%) y la incapacidad para atenuarla crisis del clima, una tremenda ruptura de la solidaridad entre generaciones. Es un gran abuso, que solo puede repararse a corto plazo, deflactando \u2013descontando la inflaci\u00f3n\u2013 del IRPF con criterio redistributivo, suprimiendo el impuesto del patrimonio y anulando los incrementos de la plusval\u00eda para el 2023. Esto y cumplir la promesa olvidada de S\u00e1nchez, de una reforma del sistema fiscal, ahora convertido en un sistema Frankenstein a base de acumular retoques, junto con una reforma de la Administraci\u00f3n del estado para lograr que sea eficiente en el gasto y la recaudaci\u00f3n. Trabajamos siete meses al a\u00f1o para pagar los impuestos, y a\u00fan no les basta. Se\u00f1oras y se\u00f1ores, todo esto es un abuso. Y en Catalunya todav\u00eda m\u00e1s.<\/p>\n","protected":false},"author":19,"featured_media":61830,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","footnotes":""},"categories":[796],"tags":[1199,1192,1208,1276],"class_list":["post-61833","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-blog-de-josep-miro-i-ardevol-es","tag-fiscalidad","tag-fiscalitat-es","tag-impostos-es","tag-impuestos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El gran abuso de los impuestos - Converses a Catalunya<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El gran abuso de los impuestos - Converses a Catalunya\" \/>\n<meta property=\"og:description\" content=\"Publicado en La Vanguardia el 24-10-2022 \u00bfPagamos pocos impuestos? Los estatalistas dicen que s\u00ed, porque se recauda el 36,8% del PIB, por el 40,2% en la uni\u00f3n europea. Pero esto no significa que paguemos poco, sino que unos pagan, otros se escaquean y el dise\u00f1o fiscal est\u00e1 lleno de agujeros. Debemos exigir que la fiscalidad se aborde desde la previa de la eficiencia en la recaudaci\u00f3n y en el gasto p\u00fablico. De no hacerlo as\u00ed, el debate est\u00e1 falseado, porque la condici\u00f3n necesaria para que un estado sea justo es que sea eficiente en la recaudaci\u00f3n y en el gasto, y Espa\u00f1a est\u00e1 escandalosamente lejos de serlo. Los que pagamos lo hacemos en una medida muy elevada. El m\u00e1ximo por IRPF en Espa\u00f1a se sit\u00faa en el 49,1%, diez puntos m\u00e1s que en la UE. En sociedades, el tipo nominal espa\u00f1ol es del 25%, y en la UE, del 21,3%. Solo en el IVA estamos algo por encima; del 21% al 21,5%. En Europa se recauda de media un 9,9% por la v\u00eda del IRPF y en Espa\u00f1a el 8,8%. Por sociedades, el 2,45% en Europa por el 2% en Espa\u00f1a. Solo en IVA \u2013un impuesto regresivo\u2013 superamos a la media europea; 6,9% por 6,3%. Si en Espa\u00f1a los tipos son m\u00e1s altos en dos de los grandes impuestos y la recaudaci\u00f3n es menor, la causa no es que paguemos menos que en Europa, sino la ineficiencia de la Administraci\u00f3n. Por si no bastara, la cu\u00f1a fiscal, lo que pagamos por IRPF y a la seguridad social, est\u00e1 por encima de la media de la OCDE, dedic\u00e1ndole cuatro de cada diez euros de nuestro ingreso salarial. Una cu\u00f1a que crece con el presupuesto del 2023, al aumentar la base m\u00e1xima de cotizaci\u00f3n de la seguridad social un 8,6%; en realidad un 9,3% por el 0,6% del mecanismo de equidad intergeneracional. El conjunto de impuestos sobre la riqueza (inmuebles, patrimonio, sucesiones y donaciones) es del 2,42% en la zona euro, por el 2,68% en Espa\u00f1a, m\u00e1s que Dinamarca (2,64%) y Suecia (1,05%). Solo nos superan Francia, B\u00e9lgica y Grecia. Para redondearlo, el proyecto de presupuestos del estado establece un aumento del impuesto de la plusval\u00eda que puede alcanzar el 50%. La presi\u00f3n fiscal se ha venido incrementando desde el 2009, y ahora la inflaci\u00f3n nos obliga a pagar m\u00e1s ganando lo mismo, ha devaluado en un 20% el valor inmobiliario y ha degradado los Ahorros y su rentabilidad. El m\u00e1ximo beneficiario es el estado, que ingresar\u00e1, seg\u00fan Hacienda, 30.000 millones m\u00e1s. Despu\u00e9s, S\u00e1nchez devuelve solo una parte, present\u00e1ndolo casi como un esfuerzo personal. Los grandes perjudicados de toda esta historia son el \u201cpueblo del IRPF\u201d, la clase media que paga y no recibe, y las rentas inferiores, a causa del efecto del IVA, un impuesto que ser\u00e1 todo lo neutral que se quiera en t\u00e9rminos t\u00e9cnicos, pero que castiga m\u00e1s a quienes menos tienen. En el otro lado de la balanza, la ineficacia: los siete informes de la Autoridad Independiente de responsabilidad Fiscal (Airef) indican que las administraciones p\u00fablicas malgastan un m\u00ednimo de 10.086 millones. El estudio Eficiencia del gasto p\u00fablico. Medici\u00f3n y propuestas de mejora del Instituto de estudios econ\u00f3micos (IEE) se\u00f1ala que la eficiencia deber\u00eda crecer un 4% para lograr la media de la UE, y un 14% para alcanzar el promedio de la OCDE, equivalente a entre 8.000 y 27.751 millones del gasto no financiero del 2023, y todo ello cuando el salario medio del sector p\u00fablico es un 58% superior al del sector privado, sin riesgo de despido. Pero la exuberancia en el gasto no ceja. Seg\u00fan Fedea, desde el 2018 el gasto p\u00fablico ha crecido 6,6 veces m\u00e1s que el PIB. Resultado: la pesada losa de la deuda que, sobre todo, depositamos sobre las espaldas de nuestros j\u00f3venes. Hay en esto, las pensiones, el paro juvenil (26,6%) y la incapacidad para atenuarla crisis del clima, una tremenda ruptura de la solidaridad entre generaciones. Es un gran abuso, que solo puede repararse a corto plazo, deflactando \u2013descontando la inflaci\u00f3n\u2013 del IRPF con criterio redistributivo, suprimiendo el impuesto del patrimonio y anulando los incrementos de la plusval\u00eda para el 2023. Esto y cumplir la promesa olvidada de S\u00e1nchez, de una reforma del sistema fiscal, ahora convertido en un sistema Frankenstein a base de acumular retoques, junto con una reforma de la Administraci\u00f3n del estado para lograr que sea eficiente en el gasto y la recaudaci\u00f3n. Trabajamos siete meses al a\u00f1o para pagar los impuestos, y a\u00fan no les basta. Se\u00f1oras y se\u00f1ores, todo esto es un abuso. Y en Catalunya todav\u00eda m\u00e1s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/\" \/>\n<meta property=\"og:site_name\" content=\"Converses a Catalunya\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-27T10:19:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-27T10:26:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2022\/10\/impostos-1024x526-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"870\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Josep Mir\u00f3 i Ard\u00e8vol\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Josep Mir\u00f3 i Ard\u00e8vol\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/\"},\"author\":{\"name\":\"Josep Mir\u00f3 i Ard\u00e8vol\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/a9598a6786ba7d3d1c5e0de477b79370\"},\"headline\":\"El gran abuso de los impuestos\",\"datePublished\":\"2022-10-27T10:19:05+00:00\",\"dateModified\":\"2022-10-27T10:26:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/\"},\"wordCount\":800,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2022\/10\/impostos-1024x526-1.jpg\",\"keywords\":[\"Fiscalidad\",\"Fiscalitat\",\"impostos\",\"Impuestos\"],\"articleSection\":[\"El Blog de Josep Mir\u00f3 i Ard\u00e8vol (ES)\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/\",\"url\":\"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/\",\"name\":\"El gran abuso de los impuestos - Converses a Catalunya\",\"isPartOf\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2022\/10\/impostos-1024x526-1.jpg\",\"datePublished\":\"2022-10-27T10:19:05+00:00\",\"dateModified\":\"2022-10-27T10:26:31+00:00\",\"author\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/a9598a6786ba7d3d1c5e0de477b79370\"},\"breadcrumb\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/#primaryimage\",\"url\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2022\/10\/impostos-1024x526-1.jpg\",\"contentUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2022\/10\/impostos-1024x526-1.jpg\",\"width\":870,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/conversesacatalunya.cat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El gran abuso de los impuestos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#website\",\"url\":\"https:\/\/conversesacatalunya.cat\/\",\"name\":\"Converses a Catalunya\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/conversesacatalunya.cat\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/a9598a6786ba7d3d1c5e0de477b79370\",\"name\":\"Josep Mir\u00f3 i Ard\u00e8vol\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/c37e3dc881857483d6694cdf98fdedea.jpg?ver=1778480034\",\"contentUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/c37e3dc881857483d6694cdf98fdedea.jpg?ver=1778480034\",\"caption\":\"Josep Mir\u00f3 i Ard\u00e8vol\"},\"url\":\"https:\/\/conversesacatalunya.cat\/es\/author\/josep-miro-i-ardevol\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El gran abuso de los impuestos - Converses a Catalunya","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"El gran abuso de los impuestos - Converses a Catalunya","og_description":"Publicado en La Vanguardia el 24-10-2022 \u00bfPagamos pocos impuestos? Los estatalistas dicen que s\u00ed, porque se recauda el 36,8% del PIB, por el 40,2% en la uni\u00f3n europea. Pero esto no significa que paguemos poco, sino que unos pagan, otros se escaquean y el dise\u00f1o fiscal est\u00e1 lleno de agujeros. Debemos exigir que la fiscalidad se aborde desde la previa de la eficiencia en la recaudaci\u00f3n y en el gasto p\u00fablico. De no hacerlo as\u00ed, el debate est\u00e1 falseado, porque la condici\u00f3n necesaria para que un estado sea justo es que sea eficiente en la recaudaci\u00f3n y en el gasto, y Espa\u00f1a est\u00e1 escandalosamente lejos de serlo. Los que pagamos lo hacemos en una medida muy elevada. El m\u00e1ximo por IRPF en Espa\u00f1a se sit\u00faa en el 49,1%, diez puntos m\u00e1s que en la UE. En sociedades, el tipo nominal espa\u00f1ol es del 25%, y en la UE, del 21,3%. Solo en el IVA estamos algo por encima; del 21% al 21,5%. En Europa se recauda de media un 9,9% por la v\u00eda del IRPF y en Espa\u00f1a el 8,8%. Por sociedades, el 2,45% en Europa por el 2% en Espa\u00f1a. Solo en IVA \u2013un impuesto regresivo\u2013 superamos a la media europea; 6,9% por 6,3%. Si en Espa\u00f1a los tipos son m\u00e1s altos en dos de los grandes impuestos y la recaudaci\u00f3n es menor, la causa no es que paguemos menos que en Europa, sino la ineficiencia de la Administraci\u00f3n. Por si no bastara, la cu\u00f1a fiscal, lo que pagamos por IRPF y a la seguridad social, est\u00e1 por encima de la media de la OCDE, dedic\u00e1ndole cuatro de cada diez euros de nuestro ingreso salarial. Una cu\u00f1a que crece con el presupuesto del 2023, al aumentar la base m\u00e1xima de cotizaci\u00f3n de la seguridad social un 8,6%; en realidad un 9,3% por el 0,6% del mecanismo de equidad intergeneracional. El conjunto de impuestos sobre la riqueza (inmuebles, patrimonio, sucesiones y donaciones) es del 2,42% en la zona euro, por el 2,68% en Espa\u00f1a, m\u00e1s que Dinamarca (2,64%) y Suecia (1,05%). Solo nos superan Francia, B\u00e9lgica y Grecia. Para redondearlo, el proyecto de presupuestos del estado establece un aumento del impuesto de la plusval\u00eda que puede alcanzar el 50%. La presi\u00f3n fiscal se ha venido incrementando desde el 2009, y ahora la inflaci\u00f3n nos obliga a pagar m\u00e1s ganando lo mismo, ha devaluado en un 20% el valor inmobiliario y ha degradado los Ahorros y su rentabilidad. El m\u00e1ximo beneficiario es el estado, que ingresar\u00e1, seg\u00fan Hacienda, 30.000 millones m\u00e1s. Despu\u00e9s, S\u00e1nchez devuelve solo una parte, present\u00e1ndolo casi como un esfuerzo personal. Los grandes perjudicados de toda esta historia son el \u201cpueblo del IRPF\u201d, la clase media que paga y no recibe, y las rentas inferiores, a causa del efecto del IVA, un impuesto que ser\u00e1 todo lo neutral que se quiera en t\u00e9rminos t\u00e9cnicos, pero que castiga m\u00e1s a quienes menos tienen. En el otro lado de la balanza, la ineficacia: los siete informes de la Autoridad Independiente de responsabilidad Fiscal (Airef) indican que las administraciones p\u00fablicas malgastan un m\u00ednimo de 10.086 millones. El estudio Eficiencia del gasto p\u00fablico. Medici\u00f3n y propuestas de mejora del Instituto de estudios econ\u00f3micos (IEE) se\u00f1ala que la eficiencia deber\u00eda crecer un 4% para lograr la media de la UE, y un 14% para alcanzar el promedio de la OCDE, equivalente a entre 8.000 y 27.751 millones del gasto no financiero del 2023, y todo ello cuando el salario medio del sector p\u00fablico es un 58% superior al del sector privado, sin riesgo de despido. Pero la exuberancia en el gasto no ceja. Seg\u00fan Fedea, desde el 2018 el gasto p\u00fablico ha crecido 6,6 veces m\u00e1s que el PIB. Resultado: la pesada losa de la deuda que, sobre todo, depositamos sobre las espaldas de nuestros j\u00f3venes. Hay en esto, las pensiones, el paro juvenil (26,6%) y la incapacidad para atenuarla crisis del clima, una tremenda ruptura de la solidaridad entre generaciones. Es un gran abuso, que solo puede repararse a corto plazo, deflactando \u2013descontando la inflaci\u00f3n\u2013 del IRPF con criterio redistributivo, suprimiendo el impuesto del patrimonio y anulando los incrementos de la plusval\u00eda para el 2023. Esto y cumplir la promesa olvidada de S\u00e1nchez, de una reforma del sistema fiscal, ahora convertido en un sistema Frankenstein a base de acumular retoques, junto con una reforma de la Administraci\u00f3n del estado para lograr que sea eficiente en el gasto y la recaudaci\u00f3n. Trabajamos siete meses al a\u00f1o para pagar los impuestos, y a\u00fan no les basta. Se\u00f1oras y se\u00f1ores, todo esto es un abuso. Y en Catalunya todav\u00eda m\u00e1s.","og_url":"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/","og_site_name":"Converses a Catalunya","article_published_time":"2022-10-27T10:19:05+00:00","article_modified_time":"2022-10-27T10:26:31+00:00","og_image":[{"width":870,"height":450,"url":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2022\/10\/impostos-1024x526-1.jpg","type":"image\/jpeg"}],"author":"Josep Mir\u00f3 i Ard\u00e8vol","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Josep Mir\u00f3 i Ard\u00e8vol","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/#article","isPartOf":{"@id":"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/"},"author":{"name":"Josep Mir\u00f3 i Ard\u00e8vol","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/a9598a6786ba7d3d1c5e0de477b79370"},"headline":"El gran abuso de los impuestos","datePublished":"2022-10-27T10:19:05+00:00","dateModified":"2022-10-27T10:26:31+00:00","mainEntityOfPage":{"@id":"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/"},"wordCount":800,"commentCount":0,"image":{"@id":"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/#primaryimage"},"thumbnailUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2022\/10\/impostos-1024x526-1.jpg","keywords":["Fiscalidad","Fiscalitat","impostos","Impuestos"],"articleSection":["El Blog de Josep Mir\u00f3 i Ard\u00e8vol (ES)"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/","url":"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/","name":"El gran abuso de los impuestos - Converses a Catalunya","isPartOf":{"@id":"https:\/\/conversesacatalunya.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/#primaryimage"},"image":{"@id":"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/#primaryimage"},"thumbnailUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2022\/10\/impostos-1024x526-1.jpg","datePublished":"2022-10-27T10:19:05+00:00","dateModified":"2022-10-27T10:26:31+00:00","author":{"@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/a9598a6786ba7d3d1c5e0de477b79370"},"breadcrumb":{"@id":"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/#primaryimage","url":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2022\/10\/impostos-1024x526-1.jpg","contentUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2022\/10\/impostos-1024x526-1.jpg","width":870,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/conversesacatalunya.cat\/es\/el-gran-abuso-de-los-impuestos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/conversesacatalunya.cat\/es\/"},{"@type":"ListItem","position":2,"name":"El gran abuso de los impuestos"}]},{"@type":"WebSite","@id":"https:\/\/conversesacatalunya.cat\/#website","url":"https:\/\/conversesacatalunya.cat\/","name":"Converses a Catalunya","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conversesacatalunya.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/a9598a6786ba7d3d1c5e0de477b79370","name":"Josep Mir\u00f3 i Ard\u00e8vol","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/image\/","url":"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/c37e3dc881857483d6694cdf98fdedea.jpg?ver=1778480034","contentUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/c37e3dc881857483d6694cdf98fdedea.jpg?ver=1778480034","caption":"Josep Mir\u00f3 i Ard\u00e8vol"},"url":"https:\/\/conversesacatalunya.cat\/es\/author\/josep-miro-i-ardevol\/"}]}},"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/61833","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/comments?post=61833"}],"version-history":[{"count":2,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/61833\/revisions"}],"predecessor-version":[{"id":61835,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/61833\/revisions\/61835"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/media\/61830"}],"wp:attachment":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/media?parent=61833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/categories?post=61833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/tags?post=61833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}