{"id":54639,"date":"2022-02-07T12:46:35","date_gmt":"2022-02-07T11:46:35","guid":{"rendered":"https:\/\/conversesacatalunya.cat\/el-pp-sembla-lluny-dassolir-la-majoria-absoluta-a-castella-i-lleo\/"},"modified":"2022-02-07T15:09:28","modified_gmt":"2022-02-07T14:09:28","slug":"el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon","status":"publish","type":"post","link":"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/","title":{"rendered":"El PP parece lejos de alcanzar la mayor\u00eda absoluta en Castilla y Le\u00f3n"},"content":{"rendered":"<p><span>Hoy es el \u00faltimo d\u00eda que se pueden hacer p\u00fablicas las encuestas, y la \u00faltima publicada por GAD3 para el diario ABC se\u00f1ala que el ascenso del PP no s\u00f3lo se ha visto frenado, sino que <\/span><strong><span>ha disminuido su apoyo electoral<\/span><\/strong><span>, pasando del m\u00e1ximo de 38-39 diputados, que le daban las anteriores encuestas, a la actual de GAD3 de 34-37.\u00a0Cabe recordar que la mayor\u00eda absoluta est\u00e1 en 41 y, por tanto, tendr\u00eda dificultades de gobernar sin el apoyo de Vox, que sigue mejorando su porcentaje y n\u00famero de esca\u00f1os que en la actualidad y seg\u00fan la misma fuente, se situar\u00eda entre 11 y 13.<\/span><\/p>\n<p><span>Pero la cuesti\u00f3n crucial no est\u00e1 tanto en obtener la mayor\u00eda absoluta como en que el n\u00famero de diputados del PP <strong>su<\/strong><\/span><strong><span>pere a los de la izquierda sumados a los de los partidos de \u00e1mbito local<\/span><\/strong><span>.\u00a0La actual encuesta no le niega esta posibilidad, pero la sit\u00faa en un interrogante, porque el PSOE, que continuar\u00eda su declive, alcanzar\u00eda entre 25-26 esca\u00f1os (ahora ten\u00eda 35), mientras que UP se sit\u00faa entre 2 y 3.<\/span><\/p>\n<p><span><span class=\"goog-text-highlight\">La Uni\u00f3n del Pueblo Leon\u00e9s mejora en un esca\u00f1o su posici\u00f3n anterior y alcanza 2. Y parece que Soria \u00a1Ya!, entrar\u00eda con 2 esca\u00f1os porque conseguir\u00eda quedar como primera fuerza en su circunscripci\u00f3n.\u00a0<\/span>Por la parte baja de los resultados, todo este bloque no superar\u00eda al primero, pero s\u00ed que lo har\u00eda por la banda alta porque obtendr\u00eda un total de 35 esca\u00f1os, y si el PP se quedara s\u00f3lo en los 34, que es lo m\u00ednimo que le dan, tambi\u00e9n deber\u00eda <\/span><strong><span>pactar con Vox<\/span><\/strong><span>\u00a0o gobernar\u00edan los socialistas con una alianza con los partidos menores.<\/span><\/p>\n<p><span>Cs por su parte tiene dif\u00edcil obtener ninguna significaci\u00f3n porque como mucho las encuestas le dan un diputado a Francisco Igea en su circunscripci\u00f3n de Valladolid, pero no est\u00e1 del todo claro que acabe consolidando esta posici\u00f3n.<\/span><\/p>\n<p><span>Si el PP no lograra una victoria clara, es evidente que los costes para Casado ser\u00edan muy importantes porque pondr\u00eda de relieve que su presencia no ha servido para impulsar a una victoria rotunda, como la de Ayuso en Madrid, en Fern\u00e1ndez Ma\u00f1ueco, el candidato popular.\u00a0Seguramente, los errores cometidos por el PP en estos \u00faltimos d\u00edas (el trabajo de campo se ha hecho entre el 31 de enero y el 4 de febrero) pueden tener que ver con la p\u00e9rdida de impulso inicial.<\/span><\/p>\n<p><span><span class=\"goog-text-highlight\">Cabe recordar que por error, al parecer, el PP vot\u00f3 a favor de la modificaci\u00f3n del C\u00f3digo Penal que permite perseguir policialmente con penas de c\u00e1rcel a las personas que rezan o reparten folletos en las inmediaciones de las cl\u00ednicas abortistas.\u00a0<\/span>En una sociedad como es la de Castilla y Le\u00f3n en la que tiene importancia el hecho cat\u00f3lico, errores de este tipo tienen consecuencias perjudiciales para el PP y beneficia a Vox.<\/span><\/p>\n<div id=\"polls-136\" class=\"wp-polls\">\n\t<form id=\"polls_form_136\" class=\"wp-polls-form\" action=\"\/index.php\" method=\"post\">\n\t\t<p style=\"display: none;\"><input type=\"hidden\" id=\"poll_136_nonce\" name=\"wp-polls-nonce\" value=\"d6fc1c3eca\" \/><\/p>\n\t\t<p style=\"display: none;\"><input type=\"hidden\" name=\"poll_id\" value=\"136\" \/><\/p>\n\t\t<p style=\"text-align: center\"><strong>Est\u00e0s d'acord que l'estel de la Sagrada Fam\u00edlia es mantingui apagat per iniciativa de l'Ajuntament de Barcelona?<\/strong><\/p><div id=\"polls-136-ans\" class=\"wp-polls-ans\"><ul class=\"wp-polls-ul\">\n\t\t<li><input type=\"radio\" id=\"poll-answer-344\" name=\"poll_136\" value=\"344\" \/> <label for=\"poll-answer-344\">S\u00ed<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-345\" name=\"poll_136\" value=\"345\" \/> <label for=\"poll-answer-345\">No<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-346\" name=\"poll_136\" value=\"346\" \/> <label for=\"poll-answer-346\">No ho s\u00e9<\/label><\/li>\n\t\t<\/ul><p style=\"text-align: center\"><input type=\"button\" name=\"vote\" value=\"   Vota   \" class=\"Buttons\" onclick=\"poll_vote(136);\" \/><\/p><p style=\"text-align: center\"><a href=\"#ViewPollResults\" onclick=\"poll_result(136); return false;\" title=\"View Results Of This Poll\">Mira els resultats<\/a><\/p><\/div>\n\t<\/form>\n<\/div>\n<div id=\"polls-136-loading\" class=\"wp-polls-loading\"><img decoding=\"async\" data-src=\"https:\/\/conversesacatalunya.cat\/wp-content\/plugins\/wp-polls\/images\/loading.gif\" width=\"16\" height=\"16\" alt=\"Cargando ...\" title=\"Cargando ...\" class=\"wp-polls-image lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 16px; --smush-placeholder-aspect-ratio: 16\/16;\" \/>&nbsp;Cargando ...<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Hoy es el \u00faltimo d\u00eda que se pueden hacer p\u00fablicas las encuestas, y la \u00faltima publicada por GAD3 para el diario ABC se\u00f1ala que el ascenso del PP no s\u00f3lo se ha visto frenado, sino que ha disminuido su apoyo electoral, pasando del m\u00e1ximo de 38-39 diputados, que le daban las anteriores encuestas, a la actual de GAD3 de 34-37.\u00a0Cabe recordar que la mayor\u00eda absoluta est\u00e1 en 41 y, por tanto, tendr\u00eda dificultades de gobernar sin el apoyo de Vox, que sigue mejorando su porcentaje y n\u00famero de esca\u00f1os que en la actualidad y seg\u00fan la misma fuente, se situar\u00eda entre 11 y 13. Pero la cuesti\u00f3n crucial no est\u00e1 tanto en obtener la mayor\u00eda absoluta como en que el n\u00famero de diputados del PP supere a los de la izquierda sumados a los de los partidos de \u00e1mbito local.\u00a0La actual encuesta no le niega esta posibilidad, pero la sit\u00faa en un interrogante, porque el PSOE, que continuar\u00eda su declive, alcanzar\u00eda entre 25-26 esca\u00f1os (ahora ten\u00eda 35), mientras que UP se sit\u00faa entre 2 y 3. La Uni\u00f3n del Pueblo Leon\u00e9s mejora en un esca\u00f1o su posici\u00f3n anterior y alcanza 2. Y parece que Soria \u00a1Ya!, entrar\u00eda con 2 esca\u00f1os porque conseguir\u00eda quedar como primera fuerza en su circunscripci\u00f3n.\u00a0Por la parte baja de los resultados, todo este bloque no superar\u00eda al primero, pero s\u00ed que lo har\u00eda por la banda alta porque obtendr\u00eda un total de 35 esca\u00f1os, y si el PP se quedara s\u00f3lo en los 34, que es lo m\u00ednimo que le dan, tambi\u00e9n deber\u00eda pactar con Vox\u00a0o gobernar\u00edan los socialistas con una alianza con los partidos menores. Cs por su parte tiene dif\u00edcil obtener ninguna significaci\u00f3n porque como mucho las encuestas le dan un diputado a Francisco Igea en su circunscripci\u00f3n de Valladolid, pero no est\u00e1 del todo claro que acabe consolidando esta posici\u00f3n. Si el PP no lograra una victoria clara, es evidente que los costes para Casado ser\u00edan muy importantes porque pondr\u00eda de relieve que su presencia no ha servido para impulsar a una victoria rotunda, como la de Ayuso en Madrid, en Fern\u00e1ndez Ma\u00f1ueco, el candidato popular.\u00a0Seguramente, los errores cometidos por el PP en estos \u00faltimos d\u00edas (el trabajo de campo se ha hecho entre el 31 de enero y el 4 de febrero) pueden tener que ver con la p\u00e9rdida de impulso inicial. Cabe recordar que por error, al parecer, el PP vot\u00f3 a favor de la modificaci\u00f3n del C\u00f3digo Penal que permite perseguir policialmente con penas de c\u00e1rcel a las personas que rezan o reparten folletos en las inmediaciones de las cl\u00ednicas abortistas.\u00a0En una sociedad como es la de Castilla y Le\u00f3n en la que tiene importancia el hecho cat\u00f3lico, errores de este tipo tienen consecuencias perjudiciales para el PP y beneficia a Vox.<\/p>\n","protected":false},"author":2,"featured_media":54636,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","footnotes":""},"categories":[806],"tags":[4478,4477],"class_list":["post-54639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-punts-claus-del-dia-es","tag-elecciones-castilla-leon","tag-eleccions-castella-lleo-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El PP parece lejos de alcanzar la mayor\u00eda absoluta en Castilla y Le\u00f3n - Converses a Catalunya<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El PP parece lejos de alcanzar la mayor\u00eda absoluta en Castilla y Le\u00f3n - Converses a Catalunya\" \/>\n<meta property=\"og:description\" content=\"Hoy es el \u00faltimo d\u00eda que se pueden hacer p\u00fablicas las encuestas, y la \u00faltima publicada por GAD3 para el diario ABC se\u00f1ala que el ascenso del PP no s\u00f3lo se ha visto frenado, sino que ha disminuido su apoyo electoral, pasando del m\u00e1ximo de 38-39 diputados, que le daban las anteriores encuestas, a la actual de GAD3 de 34-37.\u00a0Cabe recordar que la mayor\u00eda absoluta est\u00e1 en 41 y, por tanto, tendr\u00eda dificultades de gobernar sin el apoyo de Vox, que sigue mejorando su porcentaje y n\u00famero de esca\u00f1os que en la actualidad y seg\u00fan la misma fuente, se situar\u00eda entre 11 y 13. Pero la cuesti\u00f3n crucial no est\u00e1 tanto en obtener la mayor\u00eda absoluta como en que el n\u00famero de diputados del PP supere a los de la izquierda sumados a los de los partidos de \u00e1mbito local.\u00a0La actual encuesta no le niega esta posibilidad, pero la sit\u00faa en un interrogante, porque el PSOE, que continuar\u00eda su declive, alcanzar\u00eda entre 25-26 esca\u00f1os (ahora ten\u00eda 35), mientras que UP se sit\u00faa entre 2 y 3. La Uni\u00f3n del Pueblo Leon\u00e9s mejora en un esca\u00f1o su posici\u00f3n anterior y alcanza 2. Y parece que Soria \u00a1Ya!, entrar\u00eda con 2 esca\u00f1os porque conseguir\u00eda quedar como primera fuerza en su circunscripci\u00f3n.\u00a0Por la parte baja de los resultados, todo este bloque no superar\u00eda al primero, pero s\u00ed que lo har\u00eda por la banda alta porque obtendr\u00eda un total de 35 esca\u00f1os, y si el PP se quedara s\u00f3lo en los 34, que es lo m\u00ednimo que le dan, tambi\u00e9n deber\u00eda pactar con Vox\u00a0o gobernar\u00edan los socialistas con una alianza con los partidos menores. Cs por su parte tiene dif\u00edcil obtener ninguna significaci\u00f3n porque como mucho las encuestas le dan un diputado a Francisco Igea en su circunscripci\u00f3n de Valladolid, pero no est\u00e1 del todo claro que acabe consolidando esta posici\u00f3n. Si el PP no lograra una victoria clara, es evidente que los costes para Casado ser\u00edan muy importantes porque pondr\u00eda de relieve que su presencia no ha servido para impulsar a una victoria rotunda, como la de Ayuso en Madrid, en Fern\u00e1ndez Ma\u00f1ueco, el candidato popular.\u00a0Seguramente, los errores cometidos por el PP en estos \u00faltimos d\u00edas (el trabajo de campo se ha hecho entre el 31 de enero y el 4 de febrero) pueden tener que ver con la p\u00e9rdida de impulso inicial. Cabe recordar que por error, al parecer, el PP vot\u00f3 a favor de la modificaci\u00f3n del C\u00f3digo Penal que permite perseguir policialmente con penas de c\u00e1rcel a las personas que rezan o reparten folletos en las inmediaciones de las cl\u00ednicas abortistas.\u00a0En una sociedad como es la de Castilla y Le\u00f3n en la que tiene importancia el hecho cat\u00f3lico, errores de este tipo tienen consecuencias perjudiciales para el PP y beneficia a Vox.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/\" \/>\n<meta property=\"og:site_name\" content=\"Converses a Catalunya\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-07T11:46:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-07T14:09:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2022\/02\/castella-lleo.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1360\" \/>\n\t<meta property=\"og:image:height\" content=\"906\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"conversesacatalunya\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"conversesacatalunya\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/\"},\"author\":{\"name\":\"conversesacatalunya\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/7e24d1e54a2785373ddcb275eae5ed99\"},\"headline\":\"El PP parece lejos de alcanzar la mayor\u00eda absoluta en Castilla y Le\u00f3n\",\"datePublished\":\"2022-02-07T11:46:35+00:00\",\"dateModified\":\"2022-02-07T14:09:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/\"},\"wordCount\":527,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2022\/02\/castella-lleo.jpeg\",\"keywords\":[\"Elecciones Castilla Le\u00f3n\",\"Eleccions Castella Lle\u00f3\"],\"articleSection\":[\"Punts clau del dia (ES)\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/\",\"url\":\"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/\",\"name\":\"El PP parece lejos de alcanzar la mayor\u00eda absoluta en Castilla y Le\u00f3n - Converses a Catalunya\",\"isPartOf\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2022\/02\/castella-lleo.jpeg\",\"datePublished\":\"2022-02-07T11:46:35+00:00\",\"dateModified\":\"2022-02-07T14:09:28+00:00\",\"author\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/7e24d1e54a2785373ddcb275eae5ed99\"},\"breadcrumb\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/#primaryimage\",\"url\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2022\/02\/castella-lleo.jpeg\",\"contentUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2022\/02\/castella-lleo.jpeg\",\"width\":1360,\"height\":906},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/conversesacatalunya.cat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El PP parece lejos de alcanzar la mayor\u00eda absoluta en Castilla y Le\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#website\",\"url\":\"https:\/\/conversesacatalunya.cat\/\",\"name\":\"Converses a Catalunya\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/conversesacatalunya.cat\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/7e24d1e54a2785373ddcb275eae5ed99\",\"name\":\"conversesacatalunya\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/febdfeeec89d950f01c748045a981dd2.jpg?ver=1778524314\",\"contentUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/febdfeeec89d950f01c748045a981dd2.jpg?ver=1778524314\",\"caption\":\"conversesacatalunya\"},\"url\":\"https:\/\/conversesacatalunya.cat\/es\/author\/carme_catala\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El PP parece lejos de alcanzar la mayor\u00eda absoluta en Castilla y Le\u00f3n - Converses a Catalunya","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/","og_locale":"es_ES","og_type":"article","og_title":"El PP parece lejos de alcanzar la mayor\u00eda absoluta en Castilla y Le\u00f3n - Converses a Catalunya","og_description":"Hoy es el \u00faltimo d\u00eda que se pueden hacer p\u00fablicas las encuestas, y la \u00faltima publicada por GAD3 para el diario ABC se\u00f1ala que el ascenso del PP no s\u00f3lo se ha visto frenado, sino que ha disminuido su apoyo electoral, pasando del m\u00e1ximo de 38-39 diputados, que le daban las anteriores encuestas, a la actual de GAD3 de 34-37.\u00a0Cabe recordar que la mayor\u00eda absoluta est\u00e1 en 41 y, por tanto, tendr\u00eda dificultades de gobernar sin el apoyo de Vox, que sigue mejorando su porcentaje y n\u00famero de esca\u00f1os que en la actualidad y seg\u00fan la misma fuente, se situar\u00eda entre 11 y 13. Pero la cuesti\u00f3n crucial no est\u00e1 tanto en obtener la mayor\u00eda absoluta como en que el n\u00famero de diputados del PP supere a los de la izquierda sumados a los de los partidos de \u00e1mbito local.\u00a0La actual encuesta no le niega esta posibilidad, pero la sit\u00faa en un interrogante, porque el PSOE, que continuar\u00eda su declive, alcanzar\u00eda entre 25-26 esca\u00f1os (ahora ten\u00eda 35), mientras que UP se sit\u00faa entre 2 y 3. La Uni\u00f3n del Pueblo Leon\u00e9s mejora en un esca\u00f1o su posici\u00f3n anterior y alcanza 2. Y parece que Soria \u00a1Ya!, entrar\u00eda con 2 esca\u00f1os porque conseguir\u00eda quedar como primera fuerza en su circunscripci\u00f3n.\u00a0Por la parte baja de los resultados, todo este bloque no superar\u00eda al primero, pero s\u00ed que lo har\u00eda por la banda alta porque obtendr\u00eda un total de 35 esca\u00f1os, y si el PP se quedara s\u00f3lo en los 34, que es lo m\u00ednimo que le dan, tambi\u00e9n deber\u00eda pactar con Vox\u00a0o gobernar\u00edan los socialistas con una alianza con los partidos menores. Cs por su parte tiene dif\u00edcil obtener ninguna significaci\u00f3n porque como mucho las encuestas le dan un diputado a Francisco Igea en su circunscripci\u00f3n de Valladolid, pero no est\u00e1 del todo claro que acabe consolidando esta posici\u00f3n. Si el PP no lograra una victoria clara, es evidente que los costes para Casado ser\u00edan muy importantes porque pondr\u00eda de relieve que su presencia no ha servido para impulsar a una victoria rotunda, como la de Ayuso en Madrid, en Fern\u00e1ndez Ma\u00f1ueco, el candidato popular.\u00a0Seguramente, los errores cometidos por el PP en estos \u00faltimos d\u00edas (el trabajo de campo se ha hecho entre el 31 de enero y el 4 de febrero) pueden tener que ver con la p\u00e9rdida de impulso inicial. Cabe recordar que por error, al parecer, el PP vot\u00f3 a favor de la modificaci\u00f3n del C\u00f3digo Penal que permite perseguir policialmente con penas de c\u00e1rcel a las personas que rezan o reparten folletos en las inmediaciones de las cl\u00ednicas abortistas.\u00a0En una sociedad como es la de Castilla y Le\u00f3n en la que tiene importancia el hecho cat\u00f3lico, errores de este tipo tienen consecuencias perjudiciales para el PP y beneficia a Vox.","og_url":"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/","og_site_name":"Converses a Catalunya","article_published_time":"2022-02-07T11:46:35+00:00","article_modified_time":"2022-02-07T14:09:28+00:00","og_image":[{"width":1360,"height":906,"url":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2022\/02\/castella-lleo.jpeg","type":"image\/jpeg"}],"author":"conversesacatalunya","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"conversesacatalunya","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/#article","isPartOf":{"@id":"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/"},"author":{"name":"conversesacatalunya","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/7e24d1e54a2785373ddcb275eae5ed99"},"headline":"El PP parece lejos de alcanzar la mayor\u00eda absoluta en Castilla y Le\u00f3n","datePublished":"2022-02-07T11:46:35+00:00","dateModified":"2022-02-07T14:09:28+00:00","mainEntityOfPage":{"@id":"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/"},"wordCount":527,"commentCount":0,"image":{"@id":"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/#primaryimage"},"thumbnailUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2022\/02\/castella-lleo.jpeg","keywords":["Elecciones Castilla Le\u00f3n","Eleccions Castella Lle\u00f3"],"articleSection":["Punts clau del dia (ES)"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/","url":"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/","name":"El PP parece lejos de alcanzar la mayor\u00eda absoluta en Castilla y Le\u00f3n - Converses a Catalunya","isPartOf":{"@id":"https:\/\/conversesacatalunya.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/#primaryimage"},"image":{"@id":"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/#primaryimage"},"thumbnailUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2022\/02\/castella-lleo.jpeg","datePublished":"2022-02-07T11:46:35+00:00","dateModified":"2022-02-07T14:09:28+00:00","author":{"@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/7e24d1e54a2785373ddcb275eae5ed99"},"breadcrumb":{"@id":"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/#primaryimage","url":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2022\/02\/castella-lleo.jpeg","contentUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2022\/02\/castella-lleo.jpeg","width":1360,"height":906},{"@type":"BreadcrumbList","@id":"https:\/\/conversesacatalunya.cat\/es\/el-pp-parece-lejos-de-alcanzar-la-mayoria-absoluta-en-castilla-y-leon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/conversesacatalunya.cat\/es\/"},{"@type":"ListItem","position":2,"name":"El PP parece lejos de alcanzar la mayor\u00eda absoluta en Castilla y Le\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/conversesacatalunya.cat\/#website","url":"https:\/\/conversesacatalunya.cat\/","name":"Converses a Catalunya","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conversesacatalunya.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/7e24d1e54a2785373ddcb275eae5ed99","name":"conversesacatalunya","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/image\/","url":"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/febdfeeec89d950f01c748045a981dd2.jpg?ver=1778524314","contentUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/febdfeeec89d950f01c748045a981dd2.jpg?ver=1778524314","caption":"conversesacatalunya"},"url":"https:\/\/conversesacatalunya.cat\/es\/author\/carme_catala\/"}]}},"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/54639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/comments?post=54639"}],"version-history":[{"count":2,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/54639\/revisions"}],"predecessor-version":[{"id":54641,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/54639\/revisions\/54641"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/media\/54636"}],"wp:attachment":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/media?parent=54639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/categories?post=54639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/tags?post=54639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}