{"id":48211,"date":"2021-05-20T13:23:07","date_gmt":"2021-05-20T11:23:07","guid":{"rendered":"https:\/\/conversesacatalunya.cat\/?p=48211"},"modified":"2021-05-20T15:20:25","modified_gmt":"2021-05-20T13:20:25","slug":"okupacion-gubernamental","status":"publish","type":"post","link":"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/","title":{"rendered":"La Okupaci\u00f3n gubernamental"},"content":{"rendered":"<p>La vivienda constituye una necesidad humana de primer orden. Forma parte del conjunto de bienes que resultan imprescindibles para que la vida de las personas pueda desarrollarse con la dignidad necesaria. En definitiva, se trata de disponer de algo tan b\u00e1sico como es un hogar. La Constituci\u00f3n as\u00ed lo reconoce en su art\u00edculo 47, que establece \u00a0\u201c<strong>el derecho a la vivienda<\/strong>\u201d en estos t\u00e9rminos: \u201c<em>Todos los espa\u00f1oles tienen derecho a disfrutar de una vivienda digna y adecuada. Los poderes p\u00fablicos promover\u00e1n las condiciones necesarias y establecer\u00e1n las normas pertinentes para hacer efectivo este derecho, regulando la utilizaci\u00f3n del suelo de acuerdo con el inter\u00e9s general\u201d<\/em>.<\/p>\n<p>Todo esto es tan evidente no hay ning\u00fan discurso pol\u00edtico que discrepe de las afirmaciones que acabamos de formular. A pesar de ello Espa\u00f1a es uno de los pa\u00edses de Europa que menos recursos p\u00fablicos dedica a construir viviendas que est\u00e9n al alcance del conjunto de la poblaci\u00f3n, <strong>viviendas sociales<\/strong>, tanto si son de propiedad como de alquiler. Y no ser\u00e1 por falta de agentes p\u00fablicos: en primer lugar el Gobierno del Estado, los gobiernos auton\u00f3micos, los grandes ayuntamientos, incluso las diputaciones y otras instancias locales fruto de la mancomunidad. Pero todo esto ha servido de muy poco a la vista de los resultados.<\/p>\n<p><strong>Unidas Podemos<\/strong> y sus confluencias locales hicieron de esta cuesti\u00f3n una gran bandera. Es el caso, elevado a ejemplo paradigm\u00e1tico, de la alcaldesa de Barcelona <strong>Ada Colau<\/strong>, que gan\u00f3 su notoriedad precisamente en la lucha contra los desahucios. Pero su resultado pr\u00e1ctico nada tiene que ver con el imperativo que exhibi\u00f3 en otros tiempos. Despu\u00e9s de 6 a\u00f1os en el Ayuntamiento, que no son precisamente 4 d\u00edas, su rendimiento de cuentas es <strong>muy pobre<\/strong> y sigue basado en lo que llegar\u00e1 a hacer y no en lo que ha hecho. Todo ello a pesar de contar con recursos, dado que el Ayuntamiento de Barcelona pose\u00eda unas finanzas saneadas hasta su llegada, y instrumentos no solo de \u00e1mbito local, sino tambi\u00e9n metropolitano, para actuar.<\/p>\n<p>Y qu\u00e9 decir de la <strong>Generalitat de Catalu\u00f1a,<\/strong> su balance todav\u00eda es m\u00e1s pobre. Y esto se produce en una autonom\u00eda donde la izquierda es ampliamente hegem\u00f3nica, tanto que electoralmente el centro y la derecha son residuales. Pero el problema de la vivienda no est\u00e1 entre sus prioridades. Esta situaci\u00f3nno es una exclusiva de Catalu\u00f1a, pero si es uno de lugares donde los ciudadanos pagan m\u00e1s cara la contrapartida: las <strong>okupaciones.<\/strong><\/p>\n<p>El papel <strong>del Gobierno progresista de Espa\u00f1a<\/strong> es en este \u00e1mbito lamentable. No ha hecho absolutamente nada en esta materia para incentivar el desarrollo de la vivienda en comunidades aut\u00f3nomas y municipios, y ello a pesar de disponer de la<strong> SAREB<\/strong>, La Sociedad de Gesti\u00f3n de Activos Procedentes de la Reestructuraci\u00f3n Bancaria, el llamado\u201d banco malo\u201d, que concentra gran parte del patrimonio inmobiliario de las cajas de ahorros que quebraron, y que lo convierte en uno de los principales tenedores inmobiliarios de Espa\u00f1a. Pierde dinero p\u00fablico a espuertas, pero el Gobierno nunca lo ha tocado a fondo para contribuir a la respuesta de la falta de viviendas. Puestos a perder dinero que al menos tenga una rentabilidad social.<\/p>\n<p>Este grave d\u00e9ficit social ha dado lugar a un conflicto y abuso social: la ocupaci\u00f3n de viviendas como actividad sistem\u00e1tica, que tiene su causa principal en aquella carencia, pero en la que inciden m\u00e1s factores decisivos. <strong>Uno es la inepcia de los administraciones<\/strong> <strong>p\u00fablicas<\/strong>, otro <strong>la deficiencia de la justicia<\/strong> en un doble plano, el de la legislaci\u00f3n aplicable y \u00a0el de la diligencia en tramitar los casos de ocupaci\u00f3n que se producen. Pero es el tercero de todos ellos, en un determinado sentido, el m\u00e1s grave, porque constituye un <strong>abuso de los propios gobernantes hacia los gobernados<\/strong>. Se trata de la actitud de parte de las administraciones p\u00fablicas, empezando por el propio <strong>gobierno S\u00e1nchez<\/strong>, y muy evidente en el caso de Catalu\u00f1a, y todav\u00eda m\u00e1s en el de Barcelona, actuando como c\u00f3mplices o colaboradores necesarios por acci\u00f3n u omisi\u00f3n de las okupaciones.<\/p>\n<p>El resultado final es que se han generalizado organizaciones, entre la delincuencia y la ideolog\u00eda, que ocupan pisos habitados, con el consiguiente trauma para los afectados, a los que despu\u00e9s <strong>chantajean<\/strong> solicitando dinero para abandonar aquel hogar. En otros casos, viviendas moment\u00e1neamente vac\u00edas los okupas profesionales las alquilan despu\u00e9s a otras personas, ejerciendo unos derechos que no tienen. Este problema de la okupaci\u00f3n en el \u00e1rea central de la ciudad Barcelona \u00a0ha dado pie a un maligna combinaci\u00f3n con el consumo y tr\u00e1fico de drogas<\/p>\n<p>Pero \u00bfpor qu\u00e9 sucede esto? la respuesta es muy evidente: porque <strong>estas administraciones p\u00fablicas,<\/strong> cuyos actuales responsables utilizaron la vivienda como bandera, lo que hacen ahora es resolver un problema p\u00fablico de falta de vivienda que ellos no saben abordar ni encauzar, a <strong>base de traspasar su coste a los ciudadanos,<\/strong> a la propiedad privada. Pero no la de los grandes grupos, que no parecen tener una especial queja, sino la de las\u00a0 personas que ven ocupada su residencia, \u00a0su segunda vivienda o el piso vac\u00edo que ten\u00edan para alquilar; es decir, personas como la inmensa mayor\u00eda de nosotros. Este <strong>progresismo de cart\u00f3n piedra<\/strong> descarga una vez m\u00e1s, sobre los ciudadanos y sus familias, su incapacidad para resolver problemas sociales reales.<\/p>\n<div id=\"polls-104\" class=\"wp-polls\">\n\t<form id=\"polls_form_104\" class=\"wp-polls-form\" action=\"\/index.php\" method=\"post\">\n\t\t<p style=\"display: none;\"><input type=\"hidden\" id=\"poll_104_nonce\" name=\"wp-polls-nonce\" value=\"0b0cc0566c\" \/><\/p>\n\t\t<p style=\"display: none;\"><input type=\"hidden\" name=\"poll_id\" value=\"104\" \/><\/p>\n\t\t<p style=\"text-align: center\"><strong>Creieu que el Govern d'ERC i Junts per Catalunya durar\u00e0 tota la legislatura?<\/strong><\/p><div id=\"polls-104-ans\" class=\"wp-polls-ans\"><ul class=\"wp-polls-ul\">\n\t\t<li><input type=\"radio\" id=\"poll-answer-244\" name=\"poll_104\" value=\"244\" \/> <label for=\"poll-answer-244\">Si<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-245\" name=\"poll_104\" value=\"245\" \/> <label for=\"poll-answer-245\">No<\/label><\/li>\n\t\t<li><input type=\"radio\" id=\"poll-answer-246\" name=\"poll_104\" value=\"246\" \/> <label for=\"poll-answer-246\">No ho s\u00e9<\/label><\/li>\n\t\t<\/ul><p style=\"text-align: center\"><input type=\"button\" name=\"vote\" value=\"   Vota   \" class=\"Buttons\" onclick=\"poll_vote(104);\" \/><\/p><p style=\"text-align: center\"><a href=\"#ViewPollResults\" onclick=\"poll_result(104); return false;\" title=\"View Results Of This Poll\">Mira els resultats<\/a><\/p><\/div>\n\t<\/form>\n<\/div>\n<div id=\"polls-104-loading\" class=\"wp-polls-loading\"><img decoding=\"async\" data-src=\"https:\/\/conversesacatalunya.cat\/wp-content\/plugins\/wp-polls\/images\/loading.gif\" width=\"16\" height=\"16\" alt=\"Cargando ...\" title=\"Cargando ...\" class=\"wp-polls-image lazyload\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 16px; --smush-placeholder-aspect-ratio: 16\/16;\" \/>&nbsp;Cargando ...<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>La vivienda constituye una necesidad humana de primer orden. Forma parte del conjunto de bienes que resultan imprescindibles para que la vida de las personas pueda desarrollarse con la dignidad necesaria. En definitiva, se trata de disponer de algo tan b\u00e1sico como es un hogar. La Constituci\u00f3n as\u00ed lo reconoce en su art\u00edculo 47, que establece \u00a0\u201cel derecho a la vivienda\u201d en estos t\u00e9rminos: \u201cTodos los espa\u00f1oles tienen derecho a disfrutar de una vivienda digna y adecuada. Los poderes p\u00fablicos promover\u00e1n las condiciones necesarias y establecer\u00e1n las normas pertinentes para hacer efectivo este derecho, regulando la utilizaci\u00f3n del suelo de acuerdo con el inter\u00e9s general\u201d. Todo esto es tan evidente no hay ning\u00fan discurso pol\u00edtico que discrepe de las afirmaciones que acabamos de formular. A pesar de ello Espa\u00f1a es uno de los pa\u00edses de Europa que menos recursos p\u00fablicos dedica a construir viviendas que est\u00e9n al alcance del conjunto de la poblaci\u00f3n, viviendas sociales, tanto si son de propiedad como de alquiler. Y no ser\u00e1 por falta de agentes p\u00fablicos: en primer lugar el Gobierno del Estado, los gobiernos auton\u00f3micos, los grandes ayuntamientos, incluso las diputaciones y otras instancias locales fruto de la mancomunidad. Pero todo esto ha servido de muy poco a la vista de los resultados. Unidas Podemos y sus confluencias locales hicieron de esta cuesti\u00f3n una gran bandera. Es el caso, elevado a ejemplo paradigm\u00e1tico, de la alcaldesa de Barcelona Ada Colau, que gan\u00f3 su notoriedad precisamente en la lucha contra los desahucios. Pero su resultado pr\u00e1ctico nada tiene que ver con el imperativo que exhibi\u00f3 en otros tiempos. Despu\u00e9s de 6 a\u00f1os en el Ayuntamiento, que no son precisamente 4 d\u00edas, su rendimiento de cuentas es muy pobre y sigue basado en lo que llegar\u00e1 a hacer y no en lo que ha hecho. Todo ello a pesar de contar con recursos, dado que el Ayuntamiento de Barcelona pose\u00eda unas finanzas saneadas hasta su llegada, y instrumentos no solo de \u00e1mbito local, sino tambi\u00e9n metropolitano, para actuar. Y qu\u00e9 decir de la Generalitat de Catalu\u00f1a, su balance todav\u00eda es m\u00e1s pobre. Y esto se produce en una autonom\u00eda donde la izquierda es ampliamente hegem\u00f3nica, tanto que electoralmente el centro y la derecha son residuales. Pero el problema de la vivienda no est\u00e1 entre sus prioridades. Esta situaci\u00f3nno es una exclusiva de Catalu\u00f1a, pero si es uno de lugares donde los ciudadanos pagan m\u00e1s cara la contrapartida: las okupaciones. El papel del Gobierno progresista de Espa\u00f1a es en este \u00e1mbito lamentable. No ha hecho absolutamente nada en esta materia para incentivar el desarrollo de la vivienda en comunidades aut\u00f3nomas y municipios, y ello a pesar de disponer de la SAREB, La Sociedad de Gesti\u00f3n de Activos Procedentes de la Reestructuraci\u00f3n Bancaria, el llamado\u201d banco malo\u201d, que concentra gran parte del patrimonio inmobiliario de las cajas de ahorros que quebraron, y que lo convierte en uno de los principales tenedores inmobiliarios de Espa\u00f1a. Pierde dinero p\u00fablico a espuertas, pero el Gobierno nunca lo ha tocado a fondo para contribuir a la respuesta de la falta de viviendas. Puestos a perder dinero que al menos tenga una rentabilidad social. Este grave d\u00e9ficit social ha dado lugar a un conflicto y abuso social: la ocupaci\u00f3n de viviendas como actividad sistem\u00e1tica, que tiene su causa principal en aquella carencia, pero en la que inciden m\u00e1s factores decisivos. Uno es la inepcia de los administraciones p\u00fablicas, otro la deficiencia de la justicia en un doble plano, el de la legislaci\u00f3n aplicable y \u00a0el de la diligencia en tramitar los casos de ocupaci\u00f3n que se producen. Pero es el tercero de todos ellos, en un determinado sentido, el m\u00e1s grave, porque constituye un abuso de los propios gobernantes hacia los gobernados. Se trata de la actitud de parte de las administraciones p\u00fablicas, empezando por el propio gobierno S\u00e1nchez, y muy evidente en el caso de Catalu\u00f1a, y todav\u00eda m\u00e1s en el de Barcelona, actuando como c\u00f3mplices o colaboradores necesarios por acci\u00f3n u omisi\u00f3n de las okupaciones. El resultado final es que se han generalizado organizaciones, entre la delincuencia y la ideolog\u00eda, que ocupan pisos habitados, con el consiguiente trauma para los afectados, a los que despu\u00e9s chantajean solicitando dinero para abandonar aquel hogar. En otros casos, viviendas moment\u00e1neamente vac\u00edas los okupas profesionales las alquilan despu\u00e9s a otras personas, ejerciendo unos derechos que no tienen. Este problema de la okupaci\u00f3n en el \u00e1rea central de la ciudad Barcelona \u00a0ha dado pie a un maligna combinaci\u00f3n con el consumo y tr\u00e1fico de drogas Pero \u00bfpor qu\u00e9 sucede esto? la respuesta es muy evidente: porque estas administraciones p\u00fablicas, cuyos actuales responsables utilizaron la vivienda como bandera, lo que hacen ahora es resolver un problema p\u00fablico de falta de vivienda que ellos no saben abordar ni encauzar, a base de traspasar su coste a los ciudadanos, a la propiedad privada. Pero no la de los grandes grupos, que no parecen tener una especial queja, sino la de las\u00a0 personas que ven ocupada su residencia, \u00a0su segunda vivienda o el piso vac\u00edo que ten\u00edan para alquilar; es decir, personas como la inmensa mayor\u00eda de nosotros. Este progresismo de cart\u00f3n piedra descarga una vez m\u00e1s, sobre los ciudadanos y sus familias, su incapacidad para resolver problemas sociales reales.<\/p>\n","protected":false},"author":2,"featured_media":48268,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","footnotes":""},"categories":[3787,806],"tags":[3734,1035],"class_list":["post-48211","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expedient-barcelona-es","category-punts-claus-del-dia-es","tag-okupas","tag-vivienda"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Okupaci\u00f3n gubernamental - Converses a Catalunya<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Okupaci\u00f3n gubernamental - Converses a Catalunya\" \/>\n<meta property=\"og:description\" content=\"La vivienda constituye una necesidad humana de primer orden. Forma parte del conjunto de bienes que resultan imprescindibles para que la vida de las personas pueda desarrollarse con la dignidad necesaria. En definitiva, se trata de disponer de algo tan b\u00e1sico como es un hogar. La Constituci\u00f3n as\u00ed lo reconoce en su art\u00edculo 47, que establece \u00a0\u201cel derecho a la vivienda\u201d en estos t\u00e9rminos: \u201cTodos los espa\u00f1oles tienen derecho a disfrutar de una vivienda digna y adecuada. Los poderes p\u00fablicos promover\u00e1n las condiciones necesarias y establecer\u00e1n las normas pertinentes para hacer efectivo este derecho, regulando la utilizaci\u00f3n del suelo de acuerdo con el inter\u00e9s general\u201d. Todo esto es tan evidente no hay ning\u00fan discurso pol\u00edtico que discrepe de las afirmaciones que acabamos de formular. A pesar de ello Espa\u00f1a es uno de los pa\u00edses de Europa que menos recursos p\u00fablicos dedica a construir viviendas que est\u00e9n al alcance del conjunto de la poblaci\u00f3n, viviendas sociales, tanto si son de propiedad como de alquiler. Y no ser\u00e1 por falta de agentes p\u00fablicos: en primer lugar el Gobierno del Estado, los gobiernos auton\u00f3micos, los grandes ayuntamientos, incluso las diputaciones y otras instancias locales fruto de la mancomunidad. Pero todo esto ha servido de muy poco a la vista de los resultados. Unidas Podemos y sus confluencias locales hicieron de esta cuesti\u00f3n una gran bandera. Es el caso, elevado a ejemplo paradigm\u00e1tico, de la alcaldesa de Barcelona Ada Colau, que gan\u00f3 su notoriedad precisamente en la lucha contra los desahucios. Pero su resultado pr\u00e1ctico nada tiene que ver con el imperativo que exhibi\u00f3 en otros tiempos. Despu\u00e9s de 6 a\u00f1os en el Ayuntamiento, que no son precisamente 4 d\u00edas, su rendimiento de cuentas es muy pobre y sigue basado en lo que llegar\u00e1 a hacer y no en lo que ha hecho. Todo ello a pesar de contar con recursos, dado que el Ayuntamiento de Barcelona pose\u00eda unas finanzas saneadas hasta su llegada, y instrumentos no solo de \u00e1mbito local, sino tambi\u00e9n metropolitano, para actuar. Y qu\u00e9 decir de la Generalitat de Catalu\u00f1a, su balance todav\u00eda es m\u00e1s pobre. Y esto se produce en una autonom\u00eda donde la izquierda es ampliamente hegem\u00f3nica, tanto que electoralmente el centro y la derecha son residuales. Pero el problema de la vivienda no est\u00e1 entre sus prioridades. Esta situaci\u00f3nno es una exclusiva de Catalu\u00f1a, pero si es uno de lugares donde los ciudadanos pagan m\u00e1s cara la contrapartida: las okupaciones. El papel del Gobierno progresista de Espa\u00f1a es en este \u00e1mbito lamentable. No ha hecho absolutamente nada en esta materia para incentivar el desarrollo de la vivienda en comunidades aut\u00f3nomas y municipios, y ello a pesar de disponer de la SAREB, La Sociedad de Gesti\u00f3n de Activos Procedentes de la Reestructuraci\u00f3n Bancaria, el llamado\u201d banco malo\u201d, que concentra gran parte del patrimonio inmobiliario de las cajas de ahorros que quebraron, y que lo convierte en uno de los principales tenedores inmobiliarios de Espa\u00f1a. Pierde dinero p\u00fablico a espuertas, pero el Gobierno nunca lo ha tocado a fondo para contribuir a la respuesta de la falta de viviendas. Puestos a perder dinero que al menos tenga una rentabilidad social. Este grave d\u00e9ficit social ha dado lugar a un conflicto y abuso social: la ocupaci\u00f3n de viviendas como actividad sistem\u00e1tica, que tiene su causa principal en aquella carencia, pero en la que inciden m\u00e1s factores decisivos. Uno es la inepcia de los administraciones p\u00fablicas, otro la deficiencia de la justicia en un doble plano, el de la legislaci\u00f3n aplicable y \u00a0el de la diligencia en tramitar los casos de ocupaci\u00f3n que se producen. Pero es el tercero de todos ellos, en un determinado sentido, el m\u00e1s grave, porque constituye un abuso de los propios gobernantes hacia los gobernados. Se trata de la actitud de parte de las administraciones p\u00fablicas, empezando por el propio gobierno S\u00e1nchez, y muy evidente en el caso de Catalu\u00f1a, y todav\u00eda m\u00e1s en el de Barcelona, actuando como c\u00f3mplices o colaboradores necesarios por acci\u00f3n u omisi\u00f3n de las okupaciones. El resultado final es que se han generalizado organizaciones, entre la delincuencia y la ideolog\u00eda, que ocupan pisos habitados, con el consiguiente trauma para los afectados, a los que despu\u00e9s chantajean solicitando dinero para abandonar aquel hogar. En otros casos, viviendas moment\u00e1neamente vac\u00edas los okupas profesionales las alquilan despu\u00e9s a otras personas, ejerciendo unos derechos que no tienen. Este problema de la okupaci\u00f3n en el \u00e1rea central de la ciudad Barcelona \u00a0ha dado pie a un maligna combinaci\u00f3n con el consumo y tr\u00e1fico de drogas Pero \u00bfpor qu\u00e9 sucede esto? la respuesta es muy evidente: porque estas administraciones p\u00fablicas, cuyos actuales responsables utilizaron la vivienda como bandera, lo que hacen ahora es resolver un problema p\u00fablico de falta de vivienda que ellos no saben abordar ni encauzar, a base de traspasar su coste a los ciudadanos, a la propiedad privada. Pero no la de los grandes grupos, que no parecen tener una especial queja, sino la de las\u00a0 personas que ven ocupada su residencia, \u00a0su segunda vivienda o el piso vac\u00edo que ten\u00edan para alquilar; es decir, personas como la inmensa mayor\u00eda de nosotros. Este progresismo de cart\u00f3n piedra descarga una vez m\u00e1s, sobre los ciudadanos y sus familias, su incapacidad para resolver problemas sociales reales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/\" \/>\n<meta property=\"og:site_name\" content=\"Converses a Catalunya\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-20T11:23:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-20T13:20:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2021\/05\/okupa-barcelona.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1619\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"conversesacatalunya\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"conversesacatalunya\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/\"},\"author\":{\"name\":\"conversesacatalunya\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/7e24d1e54a2785373ddcb275eae5ed99\"},\"headline\":\"La Okupaci\u00f3n gubernamental\",\"datePublished\":\"2021-05-20T11:23:07+00:00\",\"dateModified\":\"2021-05-20T13:20:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/\"},\"wordCount\":945,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2021\/05\/okupa-barcelona.jpg\",\"keywords\":[\"okupas\",\"vivienda\"],\"articleSection\":[\"Expedient Barcelona (ES)\",\"Punts clau del dia (ES)\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/\",\"url\":\"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/\",\"name\":\"La Okupaci\u00f3n gubernamental - Converses a Catalunya\",\"isPartOf\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2021\/05\/okupa-barcelona.jpg\",\"datePublished\":\"2021-05-20T11:23:07+00:00\",\"dateModified\":\"2021-05-20T13:20:25+00:00\",\"author\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/7e24d1e54a2785373ddcb275eae5ed99\"},\"breadcrumb\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/#primaryimage\",\"url\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2021\/05\/okupa-barcelona.jpg\",\"contentUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2021\/05\/okupa-barcelona.jpg\",\"width\":1619,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/conversesacatalunya.cat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Okupaci\u00f3n gubernamental\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#website\",\"url\":\"https:\/\/conversesacatalunya.cat\/\",\"name\":\"Converses a Catalunya\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/conversesacatalunya.cat\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/7e24d1e54a2785373ddcb275eae5ed99\",\"name\":\"conversesacatalunya\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/febdfeeec89d950f01c748045a981dd2.jpg?ver=1778524314\",\"contentUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/febdfeeec89d950f01c748045a981dd2.jpg?ver=1778524314\",\"caption\":\"conversesacatalunya\"},\"url\":\"https:\/\/conversesacatalunya.cat\/es\/author\/carme_catala\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Okupaci\u00f3n gubernamental - Converses a Catalunya","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/","og_locale":"es_ES","og_type":"article","og_title":"La Okupaci\u00f3n gubernamental - Converses a Catalunya","og_description":"La vivienda constituye una necesidad humana de primer orden. Forma parte del conjunto de bienes que resultan imprescindibles para que la vida de las personas pueda desarrollarse con la dignidad necesaria. En definitiva, se trata de disponer de algo tan b\u00e1sico como es un hogar. La Constituci\u00f3n as\u00ed lo reconoce en su art\u00edculo 47, que establece \u00a0\u201cel derecho a la vivienda\u201d en estos t\u00e9rminos: \u201cTodos los espa\u00f1oles tienen derecho a disfrutar de una vivienda digna y adecuada. Los poderes p\u00fablicos promover\u00e1n las condiciones necesarias y establecer\u00e1n las normas pertinentes para hacer efectivo este derecho, regulando la utilizaci\u00f3n del suelo de acuerdo con el inter\u00e9s general\u201d. Todo esto es tan evidente no hay ning\u00fan discurso pol\u00edtico que discrepe de las afirmaciones que acabamos de formular. A pesar de ello Espa\u00f1a es uno de los pa\u00edses de Europa que menos recursos p\u00fablicos dedica a construir viviendas que est\u00e9n al alcance del conjunto de la poblaci\u00f3n, viviendas sociales, tanto si son de propiedad como de alquiler. Y no ser\u00e1 por falta de agentes p\u00fablicos: en primer lugar el Gobierno del Estado, los gobiernos auton\u00f3micos, los grandes ayuntamientos, incluso las diputaciones y otras instancias locales fruto de la mancomunidad. Pero todo esto ha servido de muy poco a la vista de los resultados. Unidas Podemos y sus confluencias locales hicieron de esta cuesti\u00f3n una gran bandera. Es el caso, elevado a ejemplo paradigm\u00e1tico, de la alcaldesa de Barcelona Ada Colau, que gan\u00f3 su notoriedad precisamente en la lucha contra los desahucios. Pero su resultado pr\u00e1ctico nada tiene que ver con el imperativo que exhibi\u00f3 en otros tiempos. Despu\u00e9s de 6 a\u00f1os en el Ayuntamiento, que no son precisamente 4 d\u00edas, su rendimiento de cuentas es muy pobre y sigue basado en lo que llegar\u00e1 a hacer y no en lo que ha hecho. Todo ello a pesar de contar con recursos, dado que el Ayuntamiento de Barcelona pose\u00eda unas finanzas saneadas hasta su llegada, y instrumentos no solo de \u00e1mbito local, sino tambi\u00e9n metropolitano, para actuar. Y qu\u00e9 decir de la Generalitat de Catalu\u00f1a, su balance todav\u00eda es m\u00e1s pobre. Y esto se produce en una autonom\u00eda donde la izquierda es ampliamente hegem\u00f3nica, tanto que electoralmente el centro y la derecha son residuales. Pero el problema de la vivienda no est\u00e1 entre sus prioridades. Esta situaci\u00f3nno es una exclusiva de Catalu\u00f1a, pero si es uno de lugares donde los ciudadanos pagan m\u00e1s cara la contrapartida: las okupaciones. El papel del Gobierno progresista de Espa\u00f1a es en este \u00e1mbito lamentable. No ha hecho absolutamente nada en esta materia para incentivar el desarrollo de la vivienda en comunidades aut\u00f3nomas y municipios, y ello a pesar de disponer de la SAREB, La Sociedad de Gesti\u00f3n de Activos Procedentes de la Reestructuraci\u00f3n Bancaria, el llamado\u201d banco malo\u201d, que concentra gran parte del patrimonio inmobiliario de las cajas de ahorros que quebraron, y que lo convierte en uno de los principales tenedores inmobiliarios de Espa\u00f1a. Pierde dinero p\u00fablico a espuertas, pero el Gobierno nunca lo ha tocado a fondo para contribuir a la respuesta de la falta de viviendas. Puestos a perder dinero que al menos tenga una rentabilidad social. Este grave d\u00e9ficit social ha dado lugar a un conflicto y abuso social: la ocupaci\u00f3n de viviendas como actividad sistem\u00e1tica, que tiene su causa principal en aquella carencia, pero en la que inciden m\u00e1s factores decisivos. Uno es la inepcia de los administraciones p\u00fablicas, otro la deficiencia de la justicia en un doble plano, el de la legislaci\u00f3n aplicable y \u00a0el de la diligencia en tramitar los casos de ocupaci\u00f3n que se producen. Pero es el tercero de todos ellos, en un determinado sentido, el m\u00e1s grave, porque constituye un abuso de los propios gobernantes hacia los gobernados. Se trata de la actitud de parte de las administraciones p\u00fablicas, empezando por el propio gobierno S\u00e1nchez, y muy evidente en el caso de Catalu\u00f1a, y todav\u00eda m\u00e1s en el de Barcelona, actuando como c\u00f3mplices o colaboradores necesarios por acci\u00f3n u omisi\u00f3n de las okupaciones. El resultado final es que se han generalizado organizaciones, entre la delincuencia y la ideolog\u00eda, que ocupan pisos habitados, con el consiguiente trauma para los afectados, a los que despu\u00e9s chantajean solicitando dinero para abandonar aquel hogar. En otros casos, viviendas moment\u00e1neamente vac\u00edas los okupas profesionales las alquilan despu\u00e9s a otras personas, ejerciendo unos derechos que no tienen. Este problema de la okupaci\u00f3n en el \u00e1rea central de la ciudad Barcelona \u00a0ha dado pie a un maligna combinaci\u00f3n con el consumo y tr\u00e1fico de drogas Pero \u00bfpor qu\u00e9 sucede esto? la respuesta es muy evidente: porque estas administraciones p\u00fablicas, cuyos actuales responsables utilizaron la vivienda como bandera, lo que hacen ahora es resolver un problema p\u00fablico de falta de vivienda que ellos no saben abordar ni encauzar, a base de traspasar su coste a los ciudadanos, a la propiedad privada. Pero no la de los grandes grupos, que no parecen tener una especial queja, sino la de las\u00a0 personas que ven ocupada su residencia, \u00a0su segunda vivienda o el piso vac\u00edo que ten\u00edan para alquilar; es decir, personas como la inmensa mayor\u00eda de nosotros. Este progresismo de cart\u00f3n piedra descarga una vez m\u00e1s, sobre los ciudadanos y sus familias, su incapacidad para resolver problemas sociales reales.","og_url":"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/","og_site_name":"Converses a Catalunya","article_published_time":"2021-05-20T11:23:07+00:00","article_modified_time":"2021-05-20T13:20:25+00:00","og_image":[{"width":1619,"height":1080,"url":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2021\/05\/okupa-barcelona.jpg","type":"image\/jpeg"}],"author":"conversesacatalunya","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"conversesacatalunya","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/#article","isPartOf":{"@id":"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/"},"author":{"name":"conversesacatalunya","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/7e24d1e54a2785373ddcb275eae5ed99"},"headline":"La Okupaci\u00f3n gubernamental","datePublished":"2021-05-20T11:23:07+00:00","dateModified":"2021-05-20T13:20:25+00:00","mainEntityOfPage":{"@id":"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/"},"wordCount":945,"commentCount":0,"image":{"@id":"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/#primaryimage"},"thumbnailUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2021\/05\/okupa-barcelona.jpg","keywords":["okupas","vivienda"],"articleSection":["Expedient Barcelona (ES)","Punts clau del dia (ES)"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/","url":"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/","name":"La Okupaci\u00f3n gubernamental - Converses a Catalunya","isPartOf":{"@id":"https:\/\/conversesacatalunya.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/#primaryimage"},"image":{"@id":"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/#primaryimage"},"thumbnailUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2021\/05\/okupa-barcelona.jpg","datePublished":"2021-05-20T11:23:07+00:00","dateModified":"2021-05-20T13:20:25+00:00","author":{"@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/7e24d1e54a2785373ddcb275eae5ed99"},"breadcrumb":{"@id":"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/#primaryimage","url":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2021\/05\/okupa-barcelona.jpg","contentUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2021\/05\/okupa-barcelona.jpg","width":1619,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/conversesacatalunya.cat\/es\/okupacion-gubernamental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/conversesacatalunya.cat\/es\/"},{"@type":"ListItem","position":2,"name":"La Okupaci\u00f3n gubernamental"}]},{"@type":"WebSite","@id":"https:\/\/conversesacatalunya.cat\/#website","url":"https:\/\/conversesacatalunya.cat\/","name":"Converses a Catalunya","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conversesacatalunya.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/7e24d1e54a2785373ddcb275eae5ed99","name":"conversesacatalunya","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/image\/","url":"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/febdfeeec89d950f01c748045a981dd2.jpg?ver=1778524314","contentUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/febdfeeec89d950f01c748045a981dd2.jpg?ver=1778524314","caption":"conversesacatalunya"},"url":"https:\/\/conversesacatalunya.cat\/es\/author\/carme_catala\/"}]}},"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/48211","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/comments?post=48211"}],"version-history":[{"count":3,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/48211\/revisions"}],"predecessor-version":[{"id":48270,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/48211\/revisions\/48270"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/media\/48268"}],"wp:attachment":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/media?parent=48211"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/categories?post=48211"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/tags?post=48211"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}