{"id":32847,"date":"2020-02-25T11:45:25","date_gmt":"2020-02-25T10:45:25","guid":{"rendered":"https:\/\/conversesacatalunya.cat\/per-que-pot-guanyar-trump-torna-a-ser-leconomia\/"},"modified":"2020-02-25T14:22:58","modified_gmt":"2020-02-25T13:22:58","slug":"por-que-puede-ganar-trump-vuelve-a-ser-la-economia","status":"publish","type":"post","link":"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/","title":{"rendered":"\u00bfPor qu\u00e9 puede ganar Trump? \u00a1Vuelve a ser la econom\u00eda!"},"content":{"rendered":"<p><span style=\"display: inline !important; float: none; background-color: #f5f5f5; color: rgba(0, 0, 0, 0.87); font-family: 'Roboto',arial,sans-serif; font-size: 18px; font-style: normal; font-variant: normal; font-weight: 400; letter-spacing: normal; line-height: 28px; orphans: 2; text-align: left; text-decoration: none; text-indent: 0px; text-transform: none; -webkit-text-stroke-width: 0px; white-space: pre-wrap; word-spacing: 0px;\">La campa\u00f1a electoral en los EE. UU. se encuentra en plena fase de primarias, que en realidad s\u00f3lo afecta a los dem\u00f3cratas (los republicanos tienen a Trump, un candidato incuestionado). Ofrece, de entrada, la media sorpresa de que es <strong>Bernie Sanders<\/strong> quien encabeza de manera destacada la posible nominaci\u00f3n, claramente por delante del te\u00f3rico favorito, el centrista <strong>Biden<\/strong>, que fue vicepresidente con Obama.<\/span><\/p>\n<p><span style=\"display: inline !important; float: none; background-color: #f5f5f5; color: rgba(0, 0, 0, 0.87); font-family: 'Roboto',arial,sans-serif; font-size: 18px; font-style: normal; font-variant: normal; font-weight: 400; letter-spacing: normal; line-height: 28px; orphans: 2; text-align: left; text-decoration: none; text-indent: 0px; text-transform: none; -webkit-text-stroke-width: 0px; white-space: pre-wrap; word-spacing: 0px;\">La sorpresa de Sanders es que es un candidato que <strong>se define claramente como socialista<\/strong> y procede del \u00e1mbito de los independientes. Est\u00e1 lejos de ser un \u00abpata negra\u00bb dem\u00f3crata. La relativizaci\u00f3n de la sorpresa es que este candidato parte de toda la experiencia de la campa\u00f1a anterior que le enfrent\u00f3 a la favorita y finalmente derrotada por Trump, Hilary Clinton, y que, por tanto, dispone de una m\u00e1quina bien engrasada que ha rectificado errores de la anterior campa\u00f1a, por ejemplo otorgando m\u00e1s atenci\u00f3n a los latinos, hasta el extremo de que \u00e9stos son una de sus puntas de lanza. Posiblemente la raz\u00f3n del \u00e9xito sea que, mientras el resto de los candidatos cuando se dirigen a este sector de poblaci\u00f3n s\u00f3lo les hablan de inmigraci\u00f3n, Sanders aborda toda la panoplia de <strong>temas sociales, trabajo, universidades p\u00fablicas y seguridad social a la europea<\/strong>. En definitiva, todo lo que puede interesar a un trabajador que no ha surgido de la matriz cultural anglosajona. Sanders tambi\u00e9n es el candidato dem\u00f3crata que ha recogido m\u00e1s dinero, pero todo a partir de peque\u00f1as donaciones, lo que da idea de su popularidad.<\/span><\/p>\n<p><span style=\"display: inline !important; float: none; background-color: #f5f5f5; color: rgba(0, 0, 0, 0.87); font-family: 'Roboto',arial,sans-serif; font-size: 18px; font-style: normal; font-variant: normal; font-weight: 400; letter-spacing: normal; line-height: 28px; orphans: 2; text-align: left; text-decoration: none; text-indent: 0px; text-transform: none; -webkit-text-stroke-width: 0px; white-space: pre-wrap; word-spacing: 0px;\">Ante esto, <strong>Trump goza de dos bazas muy fuertes<\/strong>. Una es que, para bien o para mal, seg\u00fan admiradores o retractores, <strong>ha ido haciendo lo que se hab\u00eda comprometido a hacer<\/strong>. No ha salido por la tangente o, al menos, lo ha hecho en muy escasa medida. Su falta de temor al conflicto lo ha ayudado. Pero evidentemente esto ser\u00eda insuficiente si no contase con la carta de la <strong>buena marcha de la econom\u00eda<\/strong>, y este ser\u00e1 sin duda su caballo de batalla ante los dem\u00f3cratas y en particular si el candidato es Sanders, porque sus propuestas evidentemente generan incertidumbre en los dem\u00f3cratas m\u00e1s cl\u00e1sicos.<\/span><\/p>\n<p><span style=\"display: inline !important; float: none; background-color: #f5f5f5; color: rgba(0, 0, 0, 0.87); font-family: 'Roboto',arial,sans-serif; font-size: 18px; font-style: normal; font-variant: normal; font-weight: 400; letter-spacing: normal; line-height: 28px; orphans: 2; text-align: left; text-decoration: none; text-indent: 0px; text-transform: none; -webkit-text-stroke-width: 0px; white-space: pre-wrap; word-spacing: 0px;\">Tres datos permiten resumir con claridad y concreci\u00f3n el \u00e9xito con el que se puede presentar Trump. El <strong>\u00edndice S&amp;P 500<\/strong> est\u00e1 en m\u00e1ximos astron\u00f3micos y ha ido creciendo desde el 20 de enero de 2017, que ya estaba arriba, cuando Trump fue elegido presidente. Para los EE. UU. esto significa que la clase media se ha enriquecido y dispone de dinero extra. Toda una baza. El <strong>ciclo econ\u00f3mico<\/strong> que comenz\u00f3 en junio de 2009 es ya el m\u00e1s largo de la historia de los EE. UU. con 127 meses, que se dice pronto, de expansi\u00f3n ininterrumpida. El anterior m\u00e1s largo fue de marzo de 1991 a marzo de 2001, y dur\u00f3 120 meses. Por \u00faltimo, la <strong>tasa de paro<\/strong> no ha hecho m\u00e1s que caer desde que fue elegido presidente, y ahora se encuentra en la cifra hist\u00f3rica del 3,6%, es decir, en plena ocupaci\u00f3n y, por tanto, en muchos sectores con falta de mano de obra. Se puede decir en contrapartida que no se ha cumplido la aspiraci\u00f3n de crecer el 4% que era una cifra astron\u00f3mica, pero ahora est\u00e1 en el 2,8%, que es una magnitud muy buena, tanto que se encuentra fuera del alcance de la Uni\u00f3n Europea. El resultado es que el <strong>44% de la poblaci\u00f3n<\/strong> considera que Trump ha reforzado la econom\u00eda, y en este amplio calado, Trump saldr\u00e1 a pescar, y si el coronavirus no lo impide, tiene perspectivas de pescar m\u00e1s que peces republicanos.<\/span><\/p>\n<span class='bctt-click-to-tweet'><span class='bctt-ctt-text'><a href='https:\/\/twitter.com\/intent\/tweet?url=https%3A%2F%2Fconversesacatalunya.cat%2Fes%2Fpor-que-puede-ganar-trump-vuelve-a-ser-la-economia%2F&#038;text=El%2044%25%20de%20la%20poblaci%C3%B3n%20de%20los%20Estados%20Unidos%20considera%20que%20Trump%20ha%20reforzado%20la%20econom%C3%ADa&#038;via=conversesacat&#038;related=conversesacat' target='_blank'rel=\"noopener noreferrer\">El 44% de la poblaci\u00f3n de los Estados Unidos considera que Trump ha reforzado la econom\u00eda <\/a><\/span><a href='https:\/\/twitter.com\/intent\/tweet?url=https%3A%2F%2Fconversesacatalunya.cat%2Fes%2Fpor-que-puede-ganar-trump-vuelve-a-ser-la-economia%2F&#038;text=El%2044%25%20de%20la%20poblaci%C3%B3n%20de%20los%20Estados%20Unidos%20considera%20que%20Trump%20ha%20reforzado%20la%20econom%C3%ADa&#038;via=conversesacat&#038;related=conversesacat' target='_blank' class='bctt-ctt-btn'rel=\"noopener noreferrer\">Compartir en X<\/a><\/span>\n","protected":false},"excerpt":{"rendered":"<p>La campa\u00f1a electoral en los EE. UU. se encuentra en plena fase de primarias, que en realidad s\u00f3lo afecta a los dem\u00f3cratas (los republicanos tienen a Trump, un candidato incuestionado). Ofrece, de entrada, la media sorpresa de que es Bernie Sanders quien encabeza de manera destacada la posible nominaci\u00f3n, claramente por delante del te\u00f3rico favorito, el centrista Biden, que fue vicepresidente con Obama. La sorpresa de Sanders es que es un candidato que se define claramente como socialista y procede del \u00e1mbito de los independientes. Est\u00e1 lejos de ser un \u00abpata negra\u00bb dem\u00f3crata. La relativizaci\u00f3n de la sorpresa es que este candidato parte de toda la experiencia de la campa\u00f1a anterior que le enfrent\u00f3 a la favorita y finalmente derrotada por Trump, Hilary Clinton, y que, por tanto, dispone de una m\u00e1quina bien engrasada que ha rectificado errores de la anterior campa\u00f1a, por ejemplo otorgando m\u00e1s atenci\u00f3n a los latinos, hasta el extremo de que \u00e9stos son una de sus puntas de lanza. Posiblemente la raz\u00f3n del \u00e9xito sea que, mientras el resto de los candidatos cuando se dirigen a este sector de poblaci\u00f3n s\u00f3lo les hablan de inmigraci\u00f3n, Sanders aborda toda la panoplia de temas sociales, trabajo, universidades p\u00fablicas y seguridad social a la europea. En definitiva, todo lo que puede interesar a un trabajador que no ha surgido de la matriz cultural anglosajona. Sanders tambi\u00e9n es el candidato dem\u00f3crata que ha recogido m\u00e1s dinero, pero todo a partir de peque\u00f1as donaciones, lo que da idea de su popularidad. Ante esto, Trump goza de dos bazas muy fuertes. Una es que, para bien o para mal, seg\u00fan admiradores o retractores, ha ido haciendo lo que se hab\u00eda comprometido a hacer. No ha salido por la tangente o, al menos, lo ha hecho en muy escasa medida. Su falta de temor al conflicto lo ha ayudado. Pero evidentemente esto ser\u00eda insuficiente si no contase con la carta de la buena marcha de la econom\u00eda, y este ser\u00e1 sin duda su caballo de batalla ante los dem\u00f3cratas y en particular si el candidato es Sanders, porque sus propuestas evidentemente generan incertidumbre en los dem\u00f3cratas m\u00e1s cl\u00e1sicos. Tres datos permiten resumir con claridad y concreci\u00f3n el \u00e9xito con el que se puede presentar Trump. El \u00edndice S&amp;P 500 est\u00e1 en m\u00e1ximos astron\u00f3micos y ha ido creciendo desde el 20 de enero de 2017, que ya estaba arriba, cuando Trump fue elegido presidente. Para los EE. UU. esto significa que la clase media se ha enriquecido y dispone de dinero extra. Toda una baza. El ciclo econ\u00f3mico que comenz\u00f3 en junio de 2009 es ya el m\u00e1s largo de la historia de los EE. UU. con 127 meses, que se dice pronto, de expansi\u00f3n ininterrumpida. El anterior m\u00e1s largo fue de marzo de 1991 a marzo de 2001, y dur\u00f3 120 meses. Por \u00faltimo, la tasa de paro no ha hecho m\u00e1s que caer desde que fue elegido presidente, y ahora se encuentra en la cifra hist\u00f3rica del 3,6%, es decir, en plena ocupaci\u00f3n y, por tanto, en muchos sectores con falta de mano de obra. Se puede decir en contrapartida que no se ha cumplido la aspiraci\u00f3n de crecer el 4% que era una cifra astron\u00f3mica, pero ahora est\u00e1 en el 2,8%, que es una magnitud muy buena, tanto que se encuentra fuera del alcance de la Uni\u00f3n Europea. El resultado es que el 44% de la poblaci\u00f3n considera que Trump ha reforzado la econom\u00eda, y en este amplio calado, Trump saldr\u00e1 a pescar, y si el coronavirus no lo impide, tiene perspectivas de pescar m\u00e1s que peces republicanos.<\/p>\n","protected":false},"author":2,"featured_media":32826,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","footnotes":""},"categories":[806],"tags":[963,1345,1758],"class_list":["post-32847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-punts-claus-del-dia-es","tag-donald-trump-es","tag-ee-uu","tag-elecciones-ee-uu"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfPor qu\u00e9 puede ganar Trump? \u00a1Vuelve a ser la econom\u00eda! - Converses a Catalunya<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfPor qu\u00e9 puede ganar Trump? \u00a1Vuelve a ser la econom\u00eda! - Converses a Catalunya\" \/>\n<meta property=\"og:description\" content=\"La campa\u00f1a electoral en los EE. UU. se encuentra en plena fase de primarias, que en realidad s\u00f3lo afecta a los dem\u00f3cratas (los republicanos tienen a Trump, un candidato incuestionado). Ofrece, de entrada, la media sorpresa de que es Bernie Sanders quien encabeza de manera destacada la posible nominaci\u00f3n, claramente por delante del te\u00f3rico favorito, el centrista Biden, que fue vicepresidente con Obama. La sorpresa de Sanders es que es un candidato que se define claramente como socialista y procede del \u00e1mbito de los independientes. Est\u00e1 lejos de ser un \u00abpata negra\u00bb dem\u00f3crata. La relativizaci\u00f3n de la sorpresa es que este candidato parte de toda la experiencia de la campa\u00f1a anterior que le enfrent\u00f3 a la favorita y finalmente derrotada por Trump, Hilary Clinton, y que, por tanto, dispone de una m\u00e1quina bien engrasada que ha rectificado errores de la anterior campa\u00f1a, por ejemplo otorgando m\u00e1s atenci\u00f3n a los latinos, hasta el extremo de que \u00e9stos son una de sus puntas de lanza. Posiblemente la raz\u00f3n del \u00e9xito sea que, mientras el resto de los candidatos cuando se dirigen a este sector de poblaci\u00f3n s\u00f3lo les hablan de inmigraci\u00f3n, Sanders aborda toda la panoplia de temas sociales, trabajo, universidades p\u00fablicas y seguridad social a la europea. En definitiva, todo lo que puede interesar a un trabajador que no ha surgido de la matriz cultural anglosajona. Sanders tambi\u00e9n es el candidato dem\u00f3crata que ha recogido m\u00e1s dinero, pero todo a partir de peque\u00f1as donaciones, lo que da idea de su popularidad. Ante esto, Trump goza de dos bazas muy fuertes. Una es que, para bien o para mal, seg\u00fan admiradores o retractores, ha ido haciendo lo que se hab\u00eda comprometido a hacer. No ha salido por la tangente o, al menos, lo ha hecho en muy escasa medida. Su falta de temor al conflicto lo ha ayudado. Pero evidentemente esto ser\u00eda insuficiente si no contase con la carta de la buena marcha de la econom\u00eda, y este ser\u00e1 sin duda su caballo de batalla ante los dem\u00f3cratas y en particular si el candidato es Sanders, porque sus propuestas evidentemente generan incertidumbre en los dem\u00f3cratas m\u00e1s cl\u00e1sicos. Tres datos permiten resumir con claridad y concreci\u00f3n el \u00e9xito con el que se puede presentar Trump. El \u00edndice S&amp;P 500 est\u00e1 en m\u00e1ximos astron\u00f3micos y ha ido creciendo desde el 20 de enero de 2017, que ya estaba arriba, cuando Trump fue elegido presidente. Para los EE. UU. esto significa que la clase media se ha enriquecido y dispone de dinero extra. Toda una baza. El ciclo econ\u00f3mico que comenz\u00f3 en junio de 2009 es ya el m\u00e1s largo de la historia de los EE. UU. con 127 meses, que se dice pronto, de expansi\u00f3n ininterrumpida. El anterior m\u00e1s largo fue de marzo de 1991 a marzo de 2001, y dur\u00f3 120 meses. Por \u00faltimo, la tasa de paro no ha hecho m\u00e1s que caer desde que fue elegido presidente, y ahora se encuentra en la cifra hist\u00f3rica del 3,6%, es decir, en plena ocupaci\u00f3n y, por tanto, en muchos sectores con falta de mano de obra. Se puede decir en contrapartida que no se ha cumplido la aspiraci\u00f3n de crecer el 4% que era una cifra astron\u00f3mica, pero ahora est\u00e1 en el 2,8%, que es una magnitud muy buena, tanto que se encuentra fuera del alcance de la Uni\u00f3n Europea. El resultado es que el 44% de la poblaci\u00f3n considera que Trump ha reforzado la econom\u00eda, y en este amplio calado, Trump saldr\u00e1 a pescar, y si el coronavirus no lo impide, tiene perspectivas de pescar m\u00e1s que peces republicanos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/\" \/>\n<meta property=\"og:site_name\" content=\"Converses a Catalunya\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-25T10:45:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-25T13:22:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2020\/02\/trump-sanders.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1100\" \/>\n\t<meta property=\"og:image:height\" content=\"619\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"conversesacatalunya\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"conversesacatalunya\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/\"},\"author\":{\"name\":\"conversesacatalunya\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/7e24d1e54a2785373ddcb275eae5ed99\"},\"headline\":\"\u00bfPor qu\u00e9 puede ganar Trump? \u00a1Vuelve a ser la econom\u00eda!\",\"datePublished\":\"2020-02-25T10:45:25+00:00\",\"dateModified\":\"2020-02-25T13:22:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/\"},\"wordCount\":664,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2020\/02\/trump-sanders.jpeg\",\"keywords\":[\"Donald Trump\",\"EE. UU.\",\"elecciones EE. UU.\"],\"articleSection\":[\"Punts clau del dia (ES)\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/\",\"url\":\"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/\",\"name\":\"\u00bfPor qu\u00e9 puede ganar Trump? \u00a1Vuelve a ser la econom\u00eda! - Converses a Catalunya\",\"isPartOf\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2020\/02\/trump-sanders.jpeg\",\"datePublished\":\"2020-02-25T10:45:25+00:00\",\"dateModified\":\"2020-02-25T13:22:58+00:00\",\"author\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/7e24d1e54a2785373ddcb275eae5ed99\"},\"breadcrumb\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/#primaryimage\",\"url\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2020\/02\/trump-sanders.jpeg\",\"contentUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2020\/02\/trump-sanders.jpeg\",\"width\":1100,\"height\":619,\"caption\":\"Trump, Sanders\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/conversesacatalunya.cat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfPor qu\u00e9 puede ganar Trump? \u00a1Vuelve a ser la econom\u00eda!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#website\",\"url\":\"https:\/\/conversesacatalunya.cat\/\",\"name\":\"Converses a Catalunya\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/conversesacatalunya.cat\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/7e24d1e54a2785373ddcb275eae5ed99\",\"name\":\"conversesacatalunya\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/febdfeeec89d950f01c748045a981dd2.jpg?ver=1778524314\",\"contentUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/febdfeeec89d950f01c748045a981dd2.jpg?ver=1778524314\",\"caption\":\"conversesacatalunya\"},\"url\":\"https:\/\/conversesacatalunya.cat\/es\/author\/carme_catala\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfPor qu\u00e9 puede ganar Trump? \u00a1Vuelve a ser la econom\u00eda! - Converses a Catalunya","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfPor qu\u00e9 puede ganar Trump? \u00a1Vuelve a ser la econom\u00eda! - Converses a Catalunya","og_description":"La campa\u00f1a electoral en los EE. UU. se encuentra en plena fase de primarias, que en realidad s\u00f3lo afecta a los dem\u00f3cratas (los republicanos tienen a Trump, un candidato incuestionado). Ofrece, de entrada, la media sorpresa de que es Bernie Sanders quien encabeza de manera destacada la posible nominaci\u00f3n, claramente por delante del te\u00f3rico favorito, el centrista Biden, que fue vicepresidente con Obama. La sorpresa de Sanders es que es un candidato que se define claramente como socialista y procede del \u00e1mbito de los independientes. Est\u00e1 lejos de ser un \u00abpata negra\u00bb dem\u00f3crata. La relativizaci\u00f3n de la sorpresa es que este candidato parte de toda la experiencia de la campa\u00f1a anterior que le enfrent\u00f3 a la favorita y finalmente derrotada por Trump, Hilary Clinton, y que, por tanto, dispone de una m\u00e1quina bien engrasada que ha rectificado errores de la anterior campa\u00f1a, por ejemplo otorgando m\u00e1s atenci\u00f3n a los latinos, hasta el extremo de que \u00e9stos son una de sus puntas de lanza. Posiblemente la raz\u00f3n del \u00e9xito sea que, mientras el resto de los candidatos cuando se dirigen a este sector de poblaci\u00f3n s\u00f3lo les hablan de inmigraci\u00f3n, Sanders aborda toda la panoplia de temas sociales, trabajo, universidades p\u00fablicas y seguridad social a la europea. En definitiva, todo lo que puede interesar a un trabajador que no ha surgido de la matriz cultural anglosajona. Sanders tambi\u00e9n es el candidato dem\u00f3crata que ha recogido m\u00e1s dinero, pero todo a partir de peque\u00f1as donaciones, lo que da idea de su popularidad. Ante esto, Trump goza de dos bazas muy fuertes. Una es que, para bien o para mal, seg\u00fan admiradores o retractores, ha ido haciendo lo que se hab\u00eda comprometido a hacer. No ha salido por la tangente o, al menos, lo ha hecho en muy escasa medida. Su falta de temor al conflicto lo ha ayudado. Pero evidentemente esto ser\u00eda insuficiente si no contase con la carta de la buena marcha de la econom\u00eda, y este ser\u00e1 sin duda su caballo de batalla ante los dem\u00f3cratas y en particular si el candidato es Sanders, porque sus propuestas evidentemente generan incertidumbre en los dem\u00f3cratas m\u00e1s cl\u00e1sicos. Tres datos permiten resumir con claridad y concreci\u00f3n el \u00e9xito con el que se puede presentar Trump. El \u00edndice S&amp;P 500 est\u00e1 en m\u00e1ximos astron\u00f3micos y ha ido creciendo desde el 20 de enero de 2017, que ya estaba arriba, cuando Trump fue elegido presidente. Para los EE. UU. esto significa que la clase media se ha enriquecido y dispone de dinero extra. Toda una baza. El ciclo econ\u00f3mico que comenz\u00f3 en junio de 2009 es ya el m\u00e1s largo de la historia de los EE. UU. con 127 meses, que se dice pronto, de expansi\u00f3n ininterrumpida. El anterior m\u00e1s largo fue de marzo de 1991 a marzo de 2001, y dur\u00f3 120 meses. Por \u00faltimo, la tasa de paro no ha hecho m\u00e1s que caer desde que fue elegido presidente, y ahora se encuentra en la cifra hist\u00f3rica del 3,6%, es decir, en plena ocupaci\u00f3n y, por tanto, en muchos sectores con falta de mano de obra. Se puede decir en contrapartida que no se ha cumplido la aspiraci\u00f3n de crecer el 4% que era una cifra astron\u00f3mica, pero ahora est\u00e1 en el 2,8%, que es una magnitud muy buena, tanto que se encuentra fuera del alcance de la Uni\u00f3n Europea. El resultado es que el 44% de la poblaci\u00f3n considera que Trump ha reforzado la econom\u00eda, y en este amplio calado, Trump saldr\u00e1 a pescar, y si el coronavirus no lo impide, tiene perspectivas de pescar m\u00e1s que peces republicanos.","og_url":"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/","og_site_name":"Converses a Catalunya","article_published_time":"2020-02-25T10:45:25+00:00","article_modified_time":"2020-02-25T13:22:58+00:00","og_image":[{"width":1100,"height":619,"url":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2020\/02\/trump-sanders.jpeg","type":"image\/jpeg"}],"author":"conversesacatalunya","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"conversesacatalunya","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/#article","isPartOf":{"@id":"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/"},"author":{"name":"conversesacatalunya","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/7e24d1e54a2785373ddcb275eae5ed99"},"headline":"\u00bfPor qu\u00e9 puede ganar Trump? \u00a1Vuelve a ser la econom\u00eda!","datePublished":"2020-02-25T10:45:25+00:00","dateModified":"2020-02-25T13:22:58+00:00","mainEntityOfPage":{"@id":"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/"},"wordCount":664,"commentCount":0,"image":{"@id":"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/#primaryimage"},"thumbnailUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2020\/02\/trump-sanders.jpeg","keywords":["Donald Trump","EE. UU.","elecciones EE. UU."],"articleSection":["Punts clau del dia (ES)"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/","url":"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/","name":"\u00bfPor qu\u00e9 puede ganar Trump? \u00a1Vuelve a ser la econom\u00eda! - Converses a Catalunya","isPartOf":{"@id":"https:\/\/conversesacatalunya.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/#primaryimage"},"image":{"@id":"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/#primaryimage"},"thumbnailUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2020\/02\/trump-sanders.jpeg","datePublished":"2020-02-25T10:45:25+00:00","dateModified":"2020-02-25T13:22:58+00:00","author":{"@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/7e24d1e54a2785373ddcb275eae5ed99"},"breadcrumb":{"@id":"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/#primaryimage","url":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2020\/02\/trump-sanders.jpeg","contentUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2020\/02\/trump-sanders.jpeg","width":1100,"height":619,"caption":"Trump, Sanders"},{"@type":"BreadcrumbList","@id":"https:\/\/conversesacatalunya.cat\/es\/por-que-puede-ganar-trump-vuelve-a-ser-la-economia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/conversesacatalunya.cat\/es\/"},{"@type":"ListItem","position":2,"name":"\u00bfPor qu\u00e9 puede ganar Trump? \u00a1Vuelve a ser la econom\u00eda!"}]},{"@type":"WebSite","@id":"https:\/\/conversesacatalunya.cat\/#website","url":"https:\/\/conversesacatalunya.cat\/","name":"Converses a Catalunya","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conversesacatalunya.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/7e24d1e54a2785373ddcb275eae5ed99","name":"conversesacatalunya","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/image\/","url":"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/febdfeeec89d950f01c748045a981dd2.jpg?ver=1778524314","contentUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/litespeed\/avatar\/febdfeeec89d950f01c748045a981dd2.jpg?ver=1778524314","caption":"conversesacatalunya"},"url":"https:\/\/conversesacatalunya.cat\/es\/author\/carme_catala\/"}]}},"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/32847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/comments?post=32847"}],"version-history":[{"count":3,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/32847\/revisions"}],"predecessor-version":[{"id":32850,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/32847\/revisions\/32850"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/media\/32826"}],"wp:attachment":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/media?parent=32847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/categories?post=32847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/tags?post=32847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}