{"id":100267,"date":"2026-07-15T05:22:36","date_gmt":"2026-07-15T03:22:36","guid":{"rendered":"https:\/\/conversesacatalunya.cat\/?p=100267"},"modified":"2026-07-15T05:39:22","modified_gmt":"2026-07-15T03:39:22","slug":"silvia-orriols-no-es-jordi-pujol","status":"publish","type":"post","link":"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/","title":{"rendered":"S\u00edlvia Orriols no es Jordi Pujol"},"content":{"rendered":"<p>Alian\u00e7a Catalana y su l\u00edder representan la gran sacudida de la pol\u00edtica catalana posterior al \u201cproc\u00e9s\u201d, con unos efectos todav\u00eda imprevisibles en las pr\u00f3ximas contiendas electorales. Es indiscutible el m\u00e9rito personal de Silvia Orriols, una aut\u00e9ntica <em>outsider<\/em> de la pol\u00edtica catalana, que durante su primer mandato en el Ayuntamiento de Ripoll <strong>resisti\u00f3 el cord\u00f3n sanitario del resto de partidos<\/strong> y acab\u00f3 alcanzando la alcald\u00eda con m\u00e1s del 30 % de los votos. Desde Ripoll, Alian\u00e7a Catalana se ha ido implantando por todo el territorio gracias al empuje de sus dirigentes y afiliados.<\/p>\n<p><strong>Alian\u00e7a Catalana<\/strong> es la reacci\u00f3n de una parte de la sociedad ante la falta de control y regulaci\u00f3n de la inmigraci\u00f3n masiva que ha recibido Catalu\u00f1a durante todo lo que llevamos de siglo. Bien mirado, <strong>no se trata tanto de una cuesti\u00f3n ideol\u00f3gica como de una reacci\u00f3n m\u00e1s primaria o instintiva.<\/strong> Los catalanes, en su conjunto, no somos una sociedad cerrada a los extranjeros, y mucho menos racista. Adem\u00e1s, la inmensa mayor\u00eda de los inmigrantes que recibimos son personas responsables y trabajadoras que han venido a ganarse una vida mejor. Pero tambi\u00e9n los hay que delinquen, que abusan de los servicios p\u00fablicos o que se niegan a aceptar las normas m\u00ednimas de convivencia de la sociedad que los acoge. La magnitud del fen\u00f3meno migratorio, la percepci\u00f3n de descontrol y la inacci\u00f3n de los distintos gobiernos ante estos problemas han dado alas a Alian\u00e7a Catalana.<\/p>\n<p>Orriols tambi\u00e9n ha sabido detectar y capitalizar pol\u00edticamente <strong>la decepci\u00f3n por el desenlace del Proc\u00e9s<\/strong>. A esos catalanes desencantados van dirigidas sus proclamas identitarias y patri\u00f3ticas, que apelan a una Catalu\u00f1a idealizada, anterior a las grandes oleadas migratorias de los siglos XX y XXI. Sus discursos presentan la independencia como un objetivo frustrado por la cobard\u00eda de los dirigentes del proc\u00e9s, pero que ella estar\u00eda dispuesta a culminar cuando tenga la oportunidad de gobernar.<\/p>\n<p>El \u00faltimo gran pol\u00edtico catal\u00e1n que construy\u00f3 su discurso sobre el patriotismo fue <strong>Jordi Pujol<\/strong>. Por eso resulta pertinente establecer una comparaci\u00f3n entre el expresident y Orriols. Pujol tambi\u00e9n inici\u00f3 su trayectoria pol\u00edtica en <strong>una \u00e9poca marcada por una gran oleada migratoria<\/strong>, la que durante el tercer cuarto del siglo pasado lleg\u00f3 principalmente desde el sur de Espa\u00f1a. Es cierto que aquellos inmigrantes eran culturalmente m\u00e1s pr\u00f3ximos, aunque las diferencias entre un catal\u00e1n y un andaluz de hace setenta a\u00f1os pod\u00edan ser, en algunos aspectos, mayores que las que hoy existen entre muchos catalanes y una parte de los reci\u00e9n llegados. Tambi\u00e9n es cierto que aquella fue una etapa de crecimiento econ\u00f3mico en la que pr\u00e1cticamente todo el mundo pod\u00eda encontrar trabajo y prosperar.<\/p>\n<p>El gran \u00e9xito pol\u00edtico de Jordi Pujol consisti\u00f3 en<strong> construir una mayor\u00eda social catalana incorporando a cientos de miles de personas nacidas fuera de Catalu\u00f1a a un proyecto colectivo de pa\u00eds.<\/strong> Pujol asumi\u00f3 la nueva realidad social que estaba emergiendo e intent\u00f3 integrarla en un solo pueblo, con la colaboraci\u00f3n imprescindible del PSC y del PSUC. Esa idea qued\u00f3 resumida en la conocida definici\u00f3n \u00abEs catal\u00e1n quien vive y trabaja en Catalu\u00f1a\u00bb, popularizada por Pujol, aunque formulada originalmente por el dirigente socialista Rafael Campalans durante la d\u00e9cada de 1930.<\/p>\n<p><strong>Esta concepci\u00f3n de la catalanidad se sit\u00faa en las ant\u00edpodas del nacionalismo identitario que hoy defiende Orriols<\/strong>, un nacionalismo que pone el acento en los or\u00edgenes culturales y en la percepci\u00f3n de una amenaza demogr\u00e1fica sobre una Catalu\u00f1a idealizada como esencialmente catalana. Poco importa que esa visi\u00f3n no encaje con la realidad social y ling\u00fc\u00edstica del pa\u00eds. A diferencia de la \u00e9poca del joven Pujol, la pol\u00edtica actual se construye menos sobre el realismo y mucho m\u00e1s sobre las emociones. Tambi\u00e9n sobre un cierto cinismo, asumido con naturalidad por todos los partidos, seg\u00fan el cual una cosa es lo que se defiende y promete desde la oposici\u00f3n y otra muy distinta lo que realmente puede hacerse cuando se gobierna.<\/p>\n<p>El pensamiento pol\u00edtico de Pujol estaba en sinton\u00eda con la corriente democristiana y social predominante en la Europa de los Treinta A\u00f1os Gloriosos (1945-1975), y conectaba con la tradici\u00f3n pol\u00edtica catalanista de ra\u00edz cat\u00f3lica anterior a la Guerra Civil. Esa tradici\u00f3n conciliaba una concepci\u00f3n cultural y espiritual del pa\u00eds con una preocupaci\u00f3n por la cohesi\u00f3n social y el bienestar de la comunidad.<strong> El objetivo prioritario de Pujol era construir la Catalu\u00f1a del futuro a partir de la realidad existente, no de una Catalu\u00f1a idealizada.<\/strong><\/p>\n<p>Impulsado por la nueva derecha europea y, m\u00e1s all\u00e1 de los maximalismos y de la ret\u00f3rica, <strong>el proyecto pol\u00edtico de Alian\u00e7a Catalana todav\u00eda est\u00e1 por definir en muchos aspectos<\/strong>. Incorpora un discurso liberal en materia econ\u00f3mica y tambi\u00e9n en cuestiones morales, con posiciones favorables al aborto y a la denominada ideolog\u00eda de g\u00e9nero que dif\u00edcilmente parecen conciliables con el componente identitario y patri\u00f3tico que constituye el eje central de su discurso y que, en teor\u00eda, deber\u00eda traducirse en una apuesta por la estabilidad y la natalidad de las familias catalanas. Pero eso parece que no importa: en la pol\u00edtica contempor\u00e1nea, las emociones son las protagonistas.<\/p>\n<p><span>Twitter:<strong><a href=\"https:\/\/x.com\/ros_arpa\" target=\"_blank\" rel=\"noopener\">@ros_arpa<\/a><\/strong><\/span><\/p>\n<p><em><strong><span dir=\"auto\">Art\u00edculo publicado en el Diari de Girona el 14 de julio de 2026<\/span><\/strong><\/em><\/p>\n<span class='bctt-click-to-tweet'><span class='bctt-ctt-text'><a href='https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fconversesacatalunya.cat%2Fes%2Fsilvia-orriols-no-es-jordi-pujol%2F&#038;text=La%20l%C3%ADder%20de%20Alian%C3%A7a%20Catalana%20representa%20una%20ruptura%20con%20el%20catalanismo%20integrador%20de%20Jordi%20Pujol%20y%20canaliza%20el%20malestar%20por%20la%20inmigraci%C3%B3n%20y%20el%20desenlace%20del%20Proc%C3%A9s.%20%40JordiPujol%20%23AC&#038;via=conversesacat&#038;related=conversesacat' target='_blank'rel=\"noopener noreferrer\">La l\u00edder de Alian\u00e7a Catalana representa una ruptura con el catalanismo integrador de Jordi Pujol y canaliza el malestar por la inmigraci\u00f3n y el desenlace del Proc\u00e9s. @JordiPujol #AC <\/a><\/span><a href='https:\/\/x.com\/intent\/tweet?url=https%3A%2F%2Fconversesacatalunya.cat%2Fes%2Fsilvia-orriols-no-es-jordi-pujol%2F&#038;text=La%20l%C3%ADder%20de%20Alian%C3%A7a%20Catalana%20representa%20una%20ruptura%20con%20el%20catalanismo%20integrador%20de%20Jordi%20Pujol%20y%20canaliza%20el%20malestar%20por%20la%20inmigraci%C3%B3n%20y%20el%20desenlace%20del%20Proc%C3%A9s.%20%40JordiPujol%20%23AC&#038;via=conversesacat&#038;related=conversesacat' target='_blank' class='bctt-ctt-btn'rel=\"noopener noreferrer\">Compartir en X<\/a><\/span>\n","protected":false},"excerpt":{"rendered":"<p>Alian\u00e7a Catalana y su l\u00edder representan la gran sacudida de la pol\u00edtica catalana posterior al \u201cproc\u00e9s\u201d, con unos efectos todav\u00eda imprevisibles en las pr\u00f3ximas contiendas electorales. Es indiscutible el m\u00e9rito personal de Silvia Orriols, una aut\u00e9ntica outsider de la pol\u00edtica catalana, que durante su primer mandato en el Ayuntamiento de Ripoll resisti\u00f3 el cord\u00f3n sanitario del resto de partidos y acab\u00f3 alcanzando la alcald\u00eda con m\u00e1s del 30 % de los votos. Desde Ripoll, Alian\u00e7a Catalana se ha ido implantando por todo el territorio gracias al empuje de sus dirigentes y afiliados. Alian\u00e7a Catalana es la reacci\u00f3n de una parte de la sociedad ante la falta de control y regulaci\u00f3n de la inmigraci\u00f3n masiva que ha recibido Catalu\u00f1a durante todo lo que llevamos de siglo. Bien mirado, no se trata tanto de una cuesti\u00f3n ideol\u00f3gica como de una reacci\u00f3n m\u00e1s primaria o instintiva. Los catalanes, en su conjunto, no somos una sociedad cerrada a los extranjeros, y mucho menos racista. Adem\u00e1s, la inmensa mayor\u00eda de los inmigrantes que recibimos son personas responsables y trabajadoras que han venido a ganarse una vida mejor. Pero tambi\u00e9n los hay que delinquen, que abusan de los servicios p\u00fablicos o que se niegan a aceptar las normas m\u00ednimas de convivencia de la sociedad que los acoge. La magnitud del fen\u00f3meno migratorio, la percepci\u00f3n de descontrol y la inacci\u00f3n de los distintos gobiernos ante estos problemas han dado alas a Alian\u00e7a Catalana. Orriols tambi\u00e9n ha sabido detectar y capitalizar pol\u00edticamente la decepci\u00f3n por el desenlace del Proc\u00e9s. A esos catalanes desencantados van dirigidas sus proclamas identitarias y patri\u00f3ticas, que apelan a una Catalu\u00f1a idealizada, anterior a las grandes oleadas migratorias de los siglos XX y XXI. Sus discursos presentan la independencia como un objetivo frustrado por la cobard\u00eda de los dirigentes del proc\u00e9s, pero que ella estar\u00eda dispuesta a culminar cuando tenga la oportunidad de gobernar. El \u00faltimo gran pol\u00edtico catal\u00e1n que construy\u00f3 su discurso sobre el patriotismo fue Jordi Pujol. Por eso resulta pertinente establecer una comparaci\u00f3n entre el expresident y Orriols. Pujol tambi\u00e9n inici\u00f3 su trayectoria pol\u00edtica en una \u00e9poca marcada por una gran oleada migratoria, la que durante el tercer cuarto del siglo pasado lleg\u00f3 principalmente desde el sur de Espa\u00f1a. Es cierto que aquellos inmigrantes eran culturalmente m\u00e1s pr\u00f3ximos, aunque las diferencias entre un catal\u00e1n y un andaluz de hace setenta a\u00f1os pod\u00edan ser, en algunos aspectos, mayores que las que hoy existen entre muchos catalanes y una parte de los reci\u00e9n llegados. Tambi\u00e9n es cierto que aquella fue una etapa de crecimiento econ\u00f3mico en la que pr\u00e1cticamente todo el mundo pod\u00eda encontrar trabajo y prosperar. El gran \u00e9xito pol\u00edtico de Jordi Pujol consisti\u00f3 en construir una mayor\u00eda social catalana incorporando a cientos de miles de personas nacidas fuera de Catalu\u00f1a a un proyecto colectivo de pa\u00eds. Pujol asumi\u00f3 la nueva realidad social que estaba emergiendo e intent\u00f3 integrarla en un solo pueblo, con la colaboraci\u00f3n imprescindible del PSC y del PSUC. Esa idea qued\u00f3 resumida en la conocida definici\u00f3n \u00abEs catal\u00e1n quien vive y trabaja en Catalu\u00f1a\u00bb, popularizada por Pujol, aunque formulada originalmente por el dirigente socialista Rafael Campalans durante la d\u00e9cada de 1930. Esta concepci\u00f3n de la catalanidad se sit\u00faa en las ant\u00edpodas del nacionalismo identitario que hoy defiende Orriols, un nacionalismo que pone el acento en los or\u00edgenes culturales y en la percepci\u00f3n de una amenaza demogr\u00e1fica sobre una Catalu\u00f1a idealizada como esencialmente catalana. Poco importa que esa visi\u00f3n no encaje con la realidad social y ling\u00fc\u00edstica del pa\u00eds. A diferencia de la \u00e9poca del joven Pujol, la pol\u00edtica actual se construye menos sobre el realismo y mucho m\u00e1s sobre las emociones. Tambi\u00e9n sobre un cierto cinismo, asumido con naturalidad por todos los partidos, seg\u00fan el cual una cosa es lo que se defiende y promete desde la oposici\u00f3n y otra muy distinta lo que realmente puede hacerse cuando se gobierna. El pensamiento pol\u00edtico de Pujol estaba en sinton\u00eda con la corriente democristiana y social predominante en la Europa de los Treinta A\u00f1os Gloriosos (1945-1975), y conectaba con la tradici\u00f3n pol\u00edtica catalanista de ra\u00edz cat\u00f3lica anterior a la Guerra Civil. Esa tradici\u00f3n conciliaba una concepci\u00f3n cultural y espiritual del pa\u00eds con una preocupaci\u00f3n por la cohesi\u00f3n social y el bienestar de la comunidad. El objetivo prioritario de Pujol era construir la Catalu\u00f1a del futuro a partir de la realidad existente, no de una Catalu\u00f1a idealizada. Impulsado por la nueva derecha europea y, m\u00e1s all\u00e1 de los maximalismos y de la ret\u00f3rica, el proyecto pol\u00edtico de Alian\u00e7a Catalana todav\u00eda est\u00e1 por definir en muchos aspectos. Incorpora un discurso liberal en materia econ\u00f3mica y tambi\u00e9n en cuestiones morales, con posiciones favorables al aborto y a la denominada ideolog\u00eda de g\u00e9nero que dif\u00edcilmente parecen conciliables con el componente identitario y patri\u00f3tico que constituye el eje central de su discurso y que, en teor\u00eda, deber\u00eda traducirse en una apuesta por la estabilidad y la natalidad de las familias catalanas. Pero eso parece que no importa: en la pol\u00edtica contempor\u00e1nea, las emociones son las protagonistas. Twitter:@ros_arpa Art\u00edculo publicado en el Diari de Girona el 14 de julio de 2026<\/p>\n","protected":false},"author":6,"featured_media":100264,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_FSMCFIC_featured_image_caption":"","_FSMCFIC_featured_image_nocaption":"","_FSMCFIC_featured_image_hide":"","footnotes":""},"categories":[801],"tags":[5524,843,5614],"class_list":["post-100267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veritas-in-caritate-es","tag-alianca-catalana-es","tag-jordi-pujol-es","tag-silvia-orriols"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>S\u00edlvia Orriols no es Jordi Pujol - Converses a Catalunya<\/title>\n<meta name=\"description\" content=\"Silvia Orriols no es Jordi Pujol: dos visiones opuestas del catalanismo, la inmigraci\u00f3n y la construcci\u00f3n nacional de Catalunya.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"S\u00edlvia Orriols no es Jordi Pujol - Converses a Catalunya\" \/>\n<meta property=\"og:description\" content=\"Silvia Orriols no es Jordi Pujol: dos visiones opuestas del catalanismo, la inmigraci\u00f3n y la construcci\u00f3n nacional de Catalunya.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/\" \/>\n<meta property=\"og:site_name\" content=\"Converses a Catalunya\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-15T03:22:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T03:39:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2026\/07\/PUJOL_JOVE_100KB.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1366\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Carles Ros Arpa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carles Ros Arpa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/\"},\"author\":{\"name\":\"Carles Ros Arpa\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/158977e8a6f4c10be20fb1e30375371b\"},\"headline\":\"S\u00edlvia Orriols no es Jordi Pujol\",\"datePublished\":\"2026-07-15T03:22:36+00:00\",\"dateModified\":\"2026-07-15T03:39:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/\"},\"wordCount\":996,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2026\/07\/PUJOL_JOVE_100KB.jpg\",\"keywords\":[\"Alian\u00e7a Catalana\",\"Jordi Pujol\",\"S\u00edlvia Orriols\"],\"articleSection\":[\"Veritas in caritate (ES)\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/\",\"url\":\"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/\",\"name\":\"S\u00edlvia Orriols no es Jordi Pujol - Converses a Catalunya\",\"isPartOf\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2026\/07\/PUJOL_JOVE_100KB.jpg\",\"datePublished\":\"2026-07-15T03:22:36+00:00\",\"dateModified\":\"2026-07-15T03:39:22+00:00\",\"author\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/158977e8a6f4c10be20fb1e30375371b\"},\"description\":\"Silvia Orriols no es Jordi Pujol: dos visiones opuestas del catalanismo, la inmigraci\u00f3n y la construcci\u00f3n nacional de Catalunya.\",\"breadcrumb\":{\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/#primaryimage\",\"url\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2026\/07\/PUJOL_JOVE_100KB.jpg\",\"contentUrl\":\"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2026\/07\/PUJOL_JOVE_100KB.jpg\",\"width\":2048,\"height\":1366,\"caption\":\"Silvia Orriols no es Jordi Pujol\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/conversesacatalunya.cat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00edlvia Orriols no es Jordi Pujol\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#website\",\"url\":\"https:\/\/conversesacatalunya.cat\/\",\"name\":\"Converses a Catalunya\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/conversesacatalunya.cat\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/158977e8a6f4c10be20fb1e30375371b\",\"name\":\"Carles Ros Arpa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/db6401ce6a486a015c92d2f4e2f91e21?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/db6401ce6a486a015c92d2f4e2f91e21?s=96&d=mm&r=g\",\"caption\":\"Carles Ros Arpa\"},\"url\":\"https:\/\/conversesacatalunya.cat\/es\/author\/carles-ros-arpa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"S\u00edlvia Orriols no es Jordi Pujol - Converses a Catalunya","description":"Silvia Orriols no es Jordi Pujol: dos visiones opuestas del catalanismo, la inmigraci\u00f3n y la construcci\u00f3n nacional de Catalunya.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/","og_locale":"es_ES","og_type":"article","og_title":"S\u00edlvia Orriols no es Jordi Pujol - Converses a Catalunya","og_description":"Silvia Orriols no es Jordi Pujol: dos visiones opuestas del catalanismo, la inmigraci\u00f3n y la construcci\u00f3n nacional de Catalunya.","og_url":"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/","og_site_name":"Converses a Catalunya","article_published_time":"2026-07-15T03:22:36+00:00","article_modified_time":"2026-07-15T03:39:22+00:00","og_image":[{"width":2048,"height":1366,"url":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2026\/07\/PUJOL_JOVE_100KB.jpg","type":"image\/jpeg"}],"author":"Carles Ros Arpa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Carles Ros Arpa","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/#article","isPartOf":{"@id":"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/"},"author":{"name":"Carles Ros Arpa","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/158977e8a6f4c10be20fb1e30375371b"},"headline":"S\u00edlvia Orriols no es Jordi Pujol","datePublished":"2026-07-15T03:22:36+00:00","dateModified":"2026-07-15T03:39:22+00:00","mainEntityOfPage":{"@id":"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/"},"wordCount":996,"commentCount":0,"image":{"@id":"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/#primaryimage"},"thumbnailUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2026\/07\/PUJOL_JOVE_100KB.jpg","keywords":["Alian\u00e7a Catalana","Jordi Pujol","S\u00edlvia Orriols"],"articleSection":["Veritas in caritate (ES)"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/","url":"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/","name":"S\u00edlvia Orriols no es Jordi Pujol - Converses a Catalunya","isPartOf":{"@id":"https:\/\/conversesacatalunya.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/#primaryimage"},"image":{"@id":"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/#primaryimage"},"thumbnailUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2026\/07\/PUJOL_JOVE_100KB.jpg","datePublished":"2026-07-15T03:22:36+00:00","dateModified":"2026-07-15T03:39:22+00:00","author":{"@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/158977e8a6f4c10be20fb1e30375371b"},"description":"Silvia Orriols no es Jordi Pujol: dos visiones opuestas del catalanismo, la inmigraci\u00f3n y la construcci\u00f3n nacional de Catalunya.","breadcrumb":{"@id":"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/#primaryimage","url":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2026\/07\/PUJOL_JOVE_100KB.jpg","contentUrl":"https:\/\/conversesacatalunya.cat\/wp-content\/uploads\/2026\/07\/PUJOL_JOVE_100KB.jpg","width":2048,"height":1366,"caption":"Silvia Orriols no es Jordi Pujol"},{"@type":"BreadcrumbList","@id":"https:\/\/conversesacatalunya.cat\/es\/silvia-orriols-no-es-jordi-pujol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/conversesacatalunya.cat\/es\/"},{"@type":"ListItem","position":2,"name":"S\u00edlvia Orriols no es Jordi Pujol"}]},{"@type":"WebSite","@id":"https:\/\/conversesacatalunya.cat\/#website","url":"https:\/\/conversesacatalunya.cat\/","name":"Converses a Catalunya","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/conversesacatalunya.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/158977e8a6f4c10be20fb1e30375371b","name":"Carles Ros Arpa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/conversesacatalunya.cat\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/db6401ce6a486a015c92d2f4e2f91e21?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/db6401ce6a486a015c92d2f4e2f91e21?s=96&d=mm&r=g","caption":"Carles Ros Arpa"},"url":"https:\/\/conversesacatalunya.cat\/es\/author\/carles-ros-arpa\/"}]}},"wps_subtitle":"La l\u00edder de Alian\u00e7a Catalana representa una ruptura con el catalanismo integrador de Jordi Pujol y canaliza el malestar por la inmigraci\u00f3n y el desenlace del Proc\u00e9s.","_links":{"self":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/100267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/comments?post=100267"}],"version-history":[{"count":4,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/100267\/revisions"}],"predecessor-version":[{"id":100269,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/posts\/100267\/revisions\/100269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/media\/100264"}],"wp:attachment":[{"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/media?parent=100267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/categories?post=100267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/conversesacatalunya.cat\/es\/wp-json\/wp\/v2\/tags?post=100267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}